{"id":4658,"date":"2025-08-13T06:41:51","date_gmt":"2025-08-13T06:41:51","guid":{"rendered":"https:\/\/korea-transmission.com\/?post_type=product&#038;p=4658"},"modified":"2025-08-13T09:08:30","modified_gmt":"2025-08-13T09:08:30","slug":"planetary-track-drive-gearbox-for-feller-bunchers","status":"publish","type":"product","link":"https:\/\/korea-transmission.com\/it\/prodotto\/planetary-track-drive-gearbox-for-feller-bunchers\/","title":{"rendered":"Riduttore epicicloidale per abbattitrici-raccoglitrici"},"content":{"rendered":"<p>Il riduttore epicicloidale per la trasmissione dei cingoli \u00e8 un sistema di trasmissione specializzato, parte integrante delle abbattitrici-raccoglitrici cingolate, macchine forestali pesanti progettate per il taglio e la raccolta di alberi in ambienti impervi. Questo riduttore epicicloidale per la trasmissione dei cingoli rappresenta un componente fondamentale del sottocarro, convertendo la potenza del motore in una coppia elevata per azionare i cingoli della macchina, consentendo una navigazione fluida su terreni irregolari, pendii ripidi e ostacoli comunemente incontrati nelle operazioni di disboscamento.<\/p>\n<p>Nella sua essenza, il riduttore epicicloidale presenta una disposizione compatta di ingranaggi planetari, tra cui un ingranaggio solare centrale, diversi ingranaggi planetari montati su un portatreno, una corona dentata esterna fissa, un albero di ingresso collegato al motore e un albero di uscita collegato ai cingoli. Questa configurazione consente un'efficiente distribuzione della potenza e una moltiplicazione della coppia.<\/p>\n<p>Durante il funzionamento, l'albero di ingresso riceve una forza rotazionale dal motore, che fa s\u00ec che gli ingranaggi planetari orbitino attorno all'ingranaggio solare, ingranando con la corona dentata. Questo movimento epicicloidale genera una coppia considerevole sull'albero di uscita, facilitando movimenti in avanti, indietro o di rotazione con un controllo preciso della velocit\u00e0. Variando i rapporti di trasmissione, il sistema ottimizza le prestazioni per compiti che richiedono elevata potenza, come la manovra in fitte foreste o la movimentazione di carichi pesanti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4509 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Feller-Bunchers.webp\" alt=\"Trasmissione a cingoli planetari per abbattitrici-raccoglitrici\" width=\"800\" height=\"800\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Feller-Bunchers.webp 800w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Feller-Bunchers-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<h2>Dimensioni della trasmissione planetaria<\/h2>\n<h3>EH 10000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4620 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1356\" height=\"748\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1.webp 1356w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1-1280x706.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1-980x541.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1-480x265.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1356px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 94.62%; text-align: center;\" colspan=\"6\"><strong>Dotato di motore idraulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 21.7653%; text-align: center;\" width=\"188\">VOAC F12-60<\/td>\n<td style=\"width: 7.19085%; text-align: center;\" width=\"178\">X = 146<\/td>\n<td style=\"width: 15.8459%; text-align: center;\" width=\"178\">VOAC F12-80<\/td>\n<td style=\"width: 23.94%; text-align: center;\" width=\"188\">X = 157<\/td>\n<td style=\"width: 10.6892%; text-align: center;\" width=\"178\">VOAC F12-110<\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\">X = 175<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 21.7653%; text-align: center;\" width=\"188\">SAUER 51C060<\/td>\n<td style=\"width: 7.19085%; text-align: center;\" width=\"178\">X = 207<\/td>\n<td style=\"width: 15.8459%; text-align: center;\" width=\"178\">SAUER 51C080<\/td>\n<td style=\"width: 23.94%; text-align: center;\" width=\"188\">X = 212<\/td>\n<td style=\"width: 10.6892%; text-align: center;\" width=\"178\">SAUER 51C110<\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\">X = 219<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 21.7653%; text-align: center;\" colspan=\"6\">Disponibili diverse esecuzioni di input su richiesta.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"height: 240px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 88.4489%; text-align: center;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\" width=\"136\">Coppia massima in uscita<\/td>\n<td style=\"width: 24.0351%; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 11.7773%; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 11.2419%; text-align: center;\" width=\"146\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 11.1081%; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 7.3742%; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 10.5996%; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 13.4422%; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 10.5929%; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 11.7773%; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 11.2419%; text-align: center;\" width=\"146\">[ litri ]<\/td>\n<td style=\"width: 11.1081%; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 7.3742%; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 10.5996%; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\">100000<\/td>\n<td style=\"width: 13.4422%; text-align: center;\">512<\/td>\n<td style=\"width: 10.5929%; text-align: center;\">1080<\/td>\n<td style=\"width: 11.7773%; text-align: center;\">410<\/td>\n<td style=\"width: 11.2419%; text-align: center;\">6.5<\/td>\n<td style=\"width: 11.1081%; text-align: center;\" width=\"136\">1500\u00f7460<\/td>\n<td style=\"width: 7.3742%; text-align: center;\" width=\"136\">42\u00f717<\/td>\n<td style=\"width: 10.5996%; text-align: center;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 88.4489%; text-align: center;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\">76.1<\/td>\n<td style=\"width: 13.4422%; text-align: center;\">86<\/td>\n<td style=\"width: 10.5929%; text-align: center;\">101.3<\/td>\n<td style=\"width: 11.7773%; text-align: center;\">114.4<\/td>\n<td style=\"width: 11.2419%; text-align: center;\">124.2<\/td>\n<td style=\"width: 11.1081%; text-align: center;\">132.4<\/td>\n<td style=\"width: 7.3742%; text-align: center;\">140.2<\/td>\n<td style=\"width: 10.5996%; text-align: center;\">153.9<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\">173.7<\/td>\n<td style=\"width: 13.4422%; text-align: center;\">185.4<\/td>\n<td style=\"width: 10.5929%; text-align: center;\" colspan=\"6\">209.3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 13000 SC CINGOLO<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4621 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1381\" height=\"753\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2.webp 1381w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2-1280x698.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2-980x534.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2-480x262.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1381px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 98.469%; text-align: center;\" colspan=\"6\"><strong>Dotato di motore idraulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.0193%; text-align: center;\" width=\"188\">VOAC F12-80<\/td>\n<td style=\"width: 7.60171%; text-align: center;\" width=\"178\">X = 157<\/td>\n<td style=\"width: 16.7024%; text-align: center;\" width=\"188\">VOAC F12-110<\/td>\n<td style=\"width: 22.1628%; text-align: center;\" width=\"544\">X = 175<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.0193%; text-align: center;\" width=\"188\">SAUER 51C080<\/td>\n<td style=\"width: 7.60171%; text-align: center;\" width=\"178\">X = 212<\/td>\n<td style=\"width: 16.7024%; text-align: center;\" width=\"188\">SAUER 51C110<\/td>\n<td style=\"width: 22.1628%; text-align: center;\" width=\"178\">X = 219<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\">SAUER 51C160<\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\">X = 240<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 98.469%; text-align: center;\" colspan=\"6\">Disponibili diverse esecuzioni di input su richiesta.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"height: 240px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.9999%; text-align: center;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 27.1948%; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 11.9914%; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 13.2762%; text-align: center;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 12.5268%; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 8.35118%; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 15.2034%; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 11.9914%; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 11.9914%; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 13.2762%; text-align: center;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 12.5268%; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 8.35118%; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\">150000<\/td>\n<td style=\"width: 15.2034%; text-align: center;\">512<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">1080<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">440<\/td>\n<td style=\"width: 13.2762%; text-align: center;\">7.5<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">2200\u00f7650<\/td>\n<td style=\"width: 12.5268%; text-align: center;\" width=\"136\">42\u00f717<\/td>\n<td style=\"width: 8.35118%; text-align: center;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.9999%; text-align: center;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\">76.1<\/td>\n<td style=\"width: 15.2034%; text-align: center;\">86<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">101.3<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">114.4<\/td>\n<td style=\"width: 13.2762%; text-align: center;\">124.2<\/td>\n<td style=\"width: 12.7409%; text-align: center;\">131<\/td>\n<td style=\"width: 12.5268%; text-align: center;\">140.2<\/td>\n<td style=\"width: 8.35118%; text-align: center;\">149<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\">168.1<\/td>\n<td style=\"width: 15.2034%; text-align: center;\">175.3<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">197.8<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">214.8<\/td>\n<td style=\"width: 13.2762%; text-align: center;\">242.3<\/td>\n<td style=\"width: 12.7409%; text-align: center;\"><\/td>\n<td style=\"width: 12.5268%; text-align: center;\"><\/td>\n<td style=\"width: 8.35118%; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 16000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4622 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1414\" height=\"779\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3.webp 1414w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3-1280x705.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3-980x540.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3-480x264.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1414px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.4325%; text-align: center;\" colspan=\"6\"><strong>Dotato di motore idraulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.3405%; text-align: center;\" width=\"178\">VOAC F12-110<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"188\">X = 175<\/td>\n<td style=\"width: 16.9165%; text-align: center;\" width=\"178\">VOAC F11-150 CETOP<\/td>\n<td style=\"width: 22.4839%; text-align: center;\" width=\"188\">X = 307<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.3405%; text-align: center;\" width=\"178\">SAUER 51C110<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"188\">X = 219<\/td>\n<td style=\"width: 16.9165%; text-align: center;\" width=\"178\">SAUER 51C160<\/td>\n<td style=\"width: 22.4839%; text-align: center;\" width=\"544\">X = 240<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.4325%; text-align: center;\" colspan=\"6\">Disponibili diverse esecuzioni di input su richiesta.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 934px; text-align: center;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 254px; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 124px; text-align: center;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 78px; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 142px; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 124px; text-align: center;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 78px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">170000<\/td>\n<td style=\"width: 142px; text-align: center;\">765<\/td>\n<td style=\"width: 112px; text-align: center;\">1660<\/td>\n<td style=\"width: 112px; text-align: center;\">680<\/td>\n<td style=\"width: 124px; text-align: center;\">11.5<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">2200\u00f7700<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">50\u00f720<\/td>\n<td style=\"width: 78px; text-align: center;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 934px; text-align: center;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">85.2<\/td>\n<td style=\"width: 142px; text-align: center;\">96.2<\/td>\n<td style=\"width: 112px; text-align: center;\">109.2<\/td>\n<td style=\"width: 112px; text-align: center;\">123.2<\/td>\n<td style=\"width: 124px; text-align: center;\">141.7<\/td>\n<td style=\"width: 119px; text-align: center;\">160<\/td>\n<td style=\"width: 117px; text-align: center;\">182.1<\/td>\n<td style=\"width: 78px; text-align: center;\">188.4<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">212.6<\/td>\n<td style=\"width: 142px; text-align: center;\">227.8<\/td>\n<td style=\"width: 112px; text-align: center;\">257.1<\/td>\n<td style=\"width: 112px; text-align: center;\"><\/td>\n<td style=\"width: 124px; text-align: center;\"><\/td>\n<td style=\"width: 119px; text-align: center;\"><\/td>\n<td style=\"width: 117px; text-align: center;\"><\/td>\n<td style=\"width: 78px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 22000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4623 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1444\" height=\"788\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4.webp 1444w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4-1280x699.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4-980x535.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4-480x262.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1444px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Dotato di motore idraulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"188\">VOAC F11-150 CETOP<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"178\">X = 307<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\">VOAC F11-250<\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\">X = 431<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"188\">SAUER 51C160<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"178\">X = 239<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\">SAUER 51V250<\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\">X = 460<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Disponibili diverse esecuzioni di input su richiesta.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 934px; text-align: center;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 254px; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 124px; text-align: center;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 78px; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 142px; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 124px; text-align: center;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 78px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">240000<\/td>\n<td style=\"width: 142px; text-align: center;\">765<\/td>\n<td style=\"width: 112px; text-align: center;\">1660<\/td>\n<td style=\"width: 112px; text-align: center;\">880<\/td>\n<td style=\"width: 124px; text-align: center;\">15<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"146\">2350\u00f7950<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">50\u00f720<\/td>\n<td style=\"width: 78px; text-align: center;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 934px; text-align: center;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">86.6<\/td>\n<td style=\"width: 142px; text-align: center;\">97.6<\/td>\n<td style=\"width: 112px; text-align: center;\">112.6<\/td>\n<td style=\"width: 112px; text-align: center;\">127.1<\/td>\n<td style=\"width: 124px; text-align: center;\">142.7<\/td>\n<td style=\"width: 119px; text-align: center;\">151.9<\/td>\n<td style=\"width: 117px; text-align: center;\">161.1<\/td>\n<td style=\"width: 78px; text-align: center;\">168.1<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">182.3<\/td>\n<td style=\"width: 142px; text-align: center;\">211<\/td>\n<td style=\"width: 112px; text-align: center;\">223.3<\/td>\n<td style=\"width: 112px; text-align: center;\">252<\/td>\n<td style=\"width: 124px; text-align: center;\"><\/td>\n<td style=\"width: 119px; text-align: center;\"><\/td>\n<td style=\"width: 117px; text-align: center;\"><\/td>\n<td style=\"width: 78px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 26000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4624 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1438\" height=\"774\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5.webp 1438w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5-1280x689.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5-980x527.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5-480x258.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1438px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Dotato di motore idraulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 23.4475%;\" width=\"178\">VOAC F11-250<\/td>\n<td style=\"text-align: center; width: 7.70878%;\" width=\"910\">X = 431<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 23.4475%;\" width=\"178\">SAUER 51V250<\/td>\n<td style=\"text-align: center; width: 7.70878%;\" width=\"188\">X = 460<\/td>\n<td style=\"text-align: center; width: 17.0236%;\" width=\"178\">SAUER 51C160<\/td>\n<td style=\"text-align: center; width: 22.591%;\" width=\"544\">X = 239<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Disponibili diverse esecuzioni di input su richiesta.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7858%; text-align: center;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.3833%; text-align: center;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 26.0171%; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 11.4561%; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 14.0257%; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 13.9186%; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 8.24411%; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.3833%; text-align: center;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 14.561%; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 11.4561%; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 11.4561%; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 14.0257%; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 13.9186%; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 8.24411%; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 13.3833%;\">280000<\/td>\n<td style=\"text-align: center; width: 14.561%;\">1080<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">2360<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">980<\/td>\n<td style=\"text-align: center; width: 12.7409%;\">18<\/td>\n<td style=\"text-align: center; width: 14.0257%;\" width=\"136\">2500\u00f71100<\/td>\n<td style=\"text-align: center; width: 13.9186%;\" width=\"136\">50\u00f720<\/td>\n<td style=\"text-align: center; width: 8.24411%;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7858%; text-align: center;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 13.3833%;\">86.6<\/td>\n<td style=\"text-align: center; width: 14.561%;\">97.6<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">112.6<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">127.1<\/td>\n<td style=\"text-align: center; width: 12.7409%;\">142.7<\/td>\n<td style=\"text-align: center; width: 14.0257%;\">151.9<\/td>\n<td style=\"text-align: center; width: 13.9186%;\">161.1<\/td>\n<td style=\"text-align: center; width: 8.24411%;\">168.1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 13.3833%;\">182.3<\/td>\n<td style=\"text-align: center; width: 14.561%;\">211<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">223.3<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">252<\/td>\n<td style=\"width: 12.7409%; text-align: center;\"><\/td>\n<td style=\"width: 14.0257%; text-align: center;\"><\/td>\n<td style=\"width: 13.9186%; text-align: center;\"><\/td>\n<td style=\"width: 8.24411%; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 33000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4625 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1463\" height=\"783\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6.webp 1463w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6-1280x685.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6-980x524.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6-480x257.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1463px, 100vw\" \/><\/p>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Dotato di motore idraulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"178\">VOAC F11-250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"910\">X = 431<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"178\">SAUER 51V250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"188\">X = 460<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"544\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Disponibili diverse esecuzioni di input su richiesta.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse; height: 185px;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; text-align: center; height: 23px;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 13.3833%; text-align: center; height: 47px;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 26.0171%; text-align: center; height: 47px;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 11.4561%; text-align: center; height: 47px;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 12.7409%; text-align: center; height: 47px;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 14.0257%; text-align: center; height: 47px;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 13.9186%; text-align: center; height: 47px;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 8.24411%; text-align: center; height: 47px;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; text-align: center; height: 23px;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 14.561%; text-align: center; height: 23px;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 11.4561%; text-align: center; height: 23px;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 11.4561%; text-align: center; height: 23px;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 12.7409%; text-align: center; height: 23px;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 14.0257%; text-align: center; height: 23px;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 13.9186%; text-align: center; height: 23px;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 8.24411%; text-align: center; height: 23px;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr style=\"height: 13.75pt;\">\n<td class=\"et27\" style=\"text-align: center; width: 13.3833%;\">350000<\/td>\n<td class=\"et28\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 14.561%;\">1120<\/td>\n<td class=\"et28\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 11.4561%;\">2550<\/td>\n<td class=\"et44\" style=\"text-align: center; width: 11.4561%;\">1280<\/td>\n<td class=\"et44\" style=\"text-align: center; width: 12.7409%;\">21<\/td>\n<td class=\"et45\" style=\"width: 14.0257%; border-right: 0.5pt solid #d1d3d4; text-align: center;\" width=\"136\"><span class=\"font3\">3550\u00f71350<\/span><\/td>\n<td class=\"et47\" style=\"width: 13.9186%; border-right: 0.5pt solid #d1d3d4; text-align: center;\" width=\"146\"><span class=\"font3\">40\u00f720<\/span><\/td>\n<td class=\"et28\" style=\"text-align: center; width: 8.24411%;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; text-align: center; height: 23px;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 14.00pt;\">\n<td class=\"et32\" style=\"text-align: center; width: 13.3833%;\">86.6<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 14.561%;\">97.6<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 11.4561%;\">112.6<\/td>\n<td class=\"et49\" style=\"text-align: center; width: 11.4561%;\">127.1<\/td>\n<td class=\"et49\" style=\"text-align: center; width: 12.7409%;\">142.7<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 14.0257%;\">151.9<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 13.9186%;\">161.1<\/td>\n<td class=\"et33\" style=\"text-align: center; width: 8.24411%;\">182.3<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et27\" style=\"text-align: center; width: 13.3833%;\">211<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 14.561%;\">223.3<\/td>\n<td class=\"et35\" style=\"text-align: center; width: 11.4561%;\">252<\/td>\n<td style=\"text-align: center; width: 11.4561%; height: 23px;\"><\/td>\n<td style=\"width: 12.7409%; text-align: center; height: 23px;\"><\/td>\n<td style=\"width: 14.0257%; text-align: center; height: 23px;\"><\/td>\n<td style=\"width: 13.9186%; text-align: center; height: 23px;\"><\/td>\n<td style=\"width: 8.24411%; text-align: center; height: 23px;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 33000 W<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4626 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1464\" height=\"797\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7.webp 1464w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7-1280x697.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7-980x534.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7-480x261.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1464px, 100vw\" \/><\/p>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Dotato di motore idraulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"178\">VOAC F11-250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"910\">X = 431<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"178\">SAUER 51V250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"188\">X = 460<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"544\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Disponibili diverse esecuzioni di input su richiesta.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"height: 189px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 13.3833%; height: 47px; text-align: center;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 26.0171%; height: 47px; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 11.4561%; height: 47px; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 12.7409%; height: 47px; text-align: center;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 14.0257%; height: 47px; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 13.9186%; height: 47px; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 8.24411%; height: 47px; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\">350000<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\">1120<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">2550<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">1280<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\">25<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">3550\u00f71350<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">40\u00f720<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 27px;\">\n<td style=\"width: 13.3833%; height: 27px; text-align: center;\">86.6<\/td>\n<td style=\"width: 14.561%; height: 27px; text-align: center;\">97.6<\/td>\n<td style=\"width: 11.4561%; height: 27px; text-align: center;\">112.6<\/td>\n<td style=\"width: 11.4561%; height: 27px; text-align: center;\">127.1<\/td>\n<td style=\"width: 12.7409%; height: 27px; text-align: center;\">142.7<\/td>\n<td style=\"width: 14.0257%; height: 27px; text-align: center;\">151.9<\/td>\n<td style=\"width: 13.9186%; height: 27px; text-align: center;\">161.1<\/td>\n<td style=\"width: 8.24411%; height: 27px; text-align: center;\">182.3<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.3833%; text-align: center;\">211<\/td>\n<td style=\"width: 14.561%; text-align: center;\">223.3<\/td>\n<td style=\"width: 11.4561%; text-align: center;\">252<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 45000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4627 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1443\" height=\"793\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8.webp 1443w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8-1280x703.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8-980x539.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8-480x264.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1443px, 100vw\" \/><\/p>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Dotato di motore idraulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"188\">VOAC F11-250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"178\">X = 431<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"188\">SAUER 51V250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"178\">X = 460<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"544\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Disponibili diverse esecuzioni di input su richiesta.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"height: 185px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 13.3833%; height: 47px; text-align: center;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 26.0171%; height: 47px; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 11.4561%; height: 47px; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 12.7409%; height: 47px; text-align: center;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 14.0257%; height: 47px; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 13.9186%; height: 47px; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 8.24411%; height: 47px; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\">450000<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\">1120<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">2550<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">1560<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\">24<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">3750\u00f71500<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">40\u00f720<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\">85.2<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\">95.9<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">110.7<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">132.3<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\">140.3<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\">158.8<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\">183.8<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\">219.6<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 60000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4628 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1432\" height=\"796\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9.webp 1432w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9-1280x712.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9-980x545.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9-480x267.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1432px, 100vw\" \/><\/p>\n<table style=\"height: 185px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Dimensione di output<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 13.3833%; height: 47px; text-align: center;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 26.0171%; height: 47px; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 11.4561%; height: 47px; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 12.7409%; height: 47px; text-align: center;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 14.0257%; height: 47px; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 13.9186%; height: 47px; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 8.24411%; height: 47px; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr style=\"height: 13.75pt;\">\n<td class=\"et11\" style=\"width: 13.3833%; text-align: center;\">685000<\/td>\n<td class=\"et12\" style=\"width: 14.561%; text-align: center;\">1380<\/td>\n<td class=\"et12\" style=\"width: 11.4561%; text-align: center;\">3050<\/td>\n<td class=\"et12\" style=\"width: 11.4561%; text-align: center;\">3120<\/td>\n<td class=\"et12\" style=\"width: 12.7409%; text-align: center;\">50<\/td>\n<td class=\"et13\" style=\"width: 14.0257%; text-align: center;\" width=\"136\"><span class=\"font3\">4000\u00f71300<\/span><\/td>\n<td class=\"et13\" style=\"width: 13.9186%; text-align: center;\" width=\"136\"><span class=\"font3\">30\u00f720<\/span><\/td>\n<td class=\"et23\" style=\"width: 8.24411%; text-align: center;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Rapporto di riduzione efficace<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 14.50pt;\">\n<td class=\"et16\" style=\"width: 13.3833%; text-align: center;\">330.7<\/td>\n<td class=\"et17\" style=\"width: 14.561%; text-align: center;\">373.1<\/td>\n<td class=\"et18\" style=\"width: 11.4561%; text-align: center;\">442.3<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 70000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4629 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10.webp\" alt=\"Dimensioni della trasmissione planetaria\" width=\"1395\" height=\"793\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10.webp 1395w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10-1280x728.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10-980x557.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10-480x273.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1395px, 100vw\" \/><\/p>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 932px; height: 23px; text-align: center;\" colspan=\"8\">Dimensione di output<\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 125px; height: 47px; text-align: center;\" width=\"146\">Coppia massima in uscita<\/td>\n<td style=\"width: 243px; height: 47px; text-align: center;\" colspan=\"2\" width=\"272\">Capacit\u00e0 dei cuscinetti<\/td>\n<td style=\"width: 107px; height: 47px; text-align: center;\" width=\"136\">Peso senza motore<\/td>\n<td style=\"width: 119px; height: 47px; text-align: center;\" width=\"136\">Quantit\u00e0 di olio<\/td>\n<td style=\"width: 131px; height: 47px; text-align: center;\" width=\"136\">Coppia frenante<\/td>\n<td style=\"width: 130px; height: 47px; text-align: center;\" width=\"136\">Pressione di apertura<\/td>\n<td style=\"width: 77px; height: 47px; text-align: center;\" width=\"136\">Pressione massima del freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 125px; height: 23px; text-align: center;\" width=\"146\">[Nm]<\/td>\n<td style=\"width: 136px; height: 23px; text-align: center;\" width=\"136\">Cd dinamico [ kN ]<\/td>\n<td style=\"width: 107px; height: 23px; text-align: center;\" width=\"136\">C0 statico [ kN ]<\/td>\n<td style=\"width: 107px; height: 23px; text-align: center;\" width=\"136\">[ kg ]<\/td>\n<td style=\"width: 119px; height: 23px; text-align: center;\" width=\"136\">[ litri ]<\/td>\n<td style=\"width: 131px; height: 23px; text-align: center;\" width=\"136\">[Nm]<\/td>\n<td style=\"width: 130px; height: 23px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<td style=\"width: 77px; height: 23px; text-align: center;\" width=\"136\">[ sbarra ]<\/td>\n<\/tr>\n<tr style=\"height: 13.75pt;\">\n<td class=\"et10\" style=\"width: 125px; text-align: center;\">865000<\/td>\n<td class=\"et11\" style=\"width: 136px; text-align: center;\">1380<\/td>\n<td class=\"et11\" style=\"width: 107px; text-align: center;\">3050<\/td>\n<td class=\"et11\" style=\"width: 107px; text-align: center;\">3120<\/td>\n<td class=\"et11\" style=\"width: 119px; text-align: center;\">50<\/td>\n<td class=\"et12\" style=\"width: 131px; text-align: center;\" width=\"136\"><span class=\"font3\">4000\u00f71700<\/span><\/td>\n<td class=\"et12\" style=\"width: 130px; text-align: center;\" width=\"136\"><span class=\"font3\">30\u00f720<\/span><\/td>\n<td class=\"et22\" style=\"width: 77px; text-align: center;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 932px; height: 23px; text-align: center;\" colspan=\"8\">Rapporto di riduzione efficace<\/td>\n<\/tr>\n<tr style=\"height: 13.75pt;\">\n<td class=\"et10\" style=\"width: 125px; text-align: center;\">287<\/td>\n<td class=\"et15\" style=\"width: 136px; text-align: center;\">323.8<\/td>\n<td class=\"et15\" style=\"width: 107px; text-align: center;\">368.6<\/td>\n<td class=\"et15\" style=\"width: 107px; text-align: center;\">415.8<\/td>\n<td class=\"et15\" style=\"width: 119px; text-align: center;\">437.7<\/td>\n<td class=\"et16\" style=\"width: 131px; text-align: center;\">493.7<\/td>\n<td style=\"width: 130px; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 77px; height: 23px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Caratteristiche del riduttore epicicloidale per cingoli Feller Buncher<\/h2>\n<ul>\n<li><strong>Elevata capacit\u00e0 di coppia<\/strong><br \/>\nIl riduttore epicicloidale a cingoli offre una capacit\u00e0 di coppia eccezionale, consentendo alle abbattitrici-raccoglitrici di gestire carichi pesanti e di attraversare terreni difficili con facilit\u00e0. Il suo sistema di ingranaggi a pi\u00f9 stadi moltiplica in modo efficiente la coppia del motore, distribuendo la forza uniformemente sugli ingranaggi epicicloidali. Questa progettazione previene il sovraccarico durante le operazioni forestali pi\u00f9 impegnative, garantendo un'erogazione di potenza costante per le operazioni di abbattimento e raccolta degli alberi, anche in condizioni di stress estremo.<\/li>\n<li><strong>Design compatto e salvaspazio<\/strong><br \/>\nThe track drive planetary gearbox features a highly compact configuration that optimizes space within the feller buncher’s undercarriage. Its epicyclic gear arrangement, consisting of sun, planet, and ring gears, achieves high reduction ratios in a small footprint. This compactness enhances the machine’s maneuverability in dense forests, improves stability on uneven ground, and reduces the overall size of the vehicle, making transportation and integration more efficient without sacrificing performance.<\/li>\n<li><strong>Durata e affidabilit\u00e0 eccezionali<\/strong><br \/>\nCostruito con materiali temprati, il riduttore di trasmissione dei cingoli \u00e8 progettato per resistere alle difficili condizioni ambientali dei cantieri forestali, tra cui polvere, umidit\u00e0 e temperature estreme. Il suo alloggiamento sigillato e la configurazione degli ingranaggi a distribuzione delle sollecitazioni riducono al minimo l'usura, garantendo un'affidabilit\u00e0 a lungo termine. Il riduttore \u00e8 specificamente progettato per resistere a vibrazioni costanti, impatti con ostacoli del terreno e alla movimentazione di legname pesante che le abbattitrici-raccoglitrici affrontano quotidianamente, riducendo i tempi di fermo e le esigenze di manutenzione.<\/li>\n<li><strong>Elevata efficienza di trasmissione di potenza<\/strong><br \/>\nGrazie a un'efficienza che spesso supera il 95%, la trasmissione epicicloidale a cingoli garantisce perdite per attrito minime durante il funzionamento. Questa elevata efficienza riduce il consumo di carburante e la generazione di calore, consentendo alle abbattitrici-raccoglitrici di operare per periodi prolungati senza sprechi di energia. Il sistema ottimizza l'equilibrio tra velocit\u00e0 e forza di trazione, risultando ideale per attivit\u00e0 come la salita di pendii ripidi o la navigazione in ambienti forestali fangosi, mantenendo al contempo un'erogazione di potenza costante.<\/li>\n<li><strong>Versatilit\u00e0 e opzioni di personalizzazione<\/strong><br \/>\nIl riduttore epicicloidale offre una notevole versatilit\u00e0 grazie a caratteristiche personalizzabili, tra cui rapporti di trasmissione variabili e design modulari adattati alle specifiche esigenze delle abbattitrici-raccoglitrici. Queste opzioni consentono una perfetta integrazione con motori idraulici o elettrici, garantendo prestazioni precise per diverse attivit\u00e0 forestali. Dalla manovrabilit\u00e0 in spazi ristretti alla gestione di carichi variabili, il riduttore si adatta agli standard di settore, consentendo aggiornamenti e configurazioni personalizzate senza difficolt\u00e0.<\/li>\n<li><strong>Controllo preciso e gioco ridotto.<\/strong><br \/>\nIl riduttore epicicloidale a trazione cingolata, grazie alle tolleranze ristrette e all'allineamento coassiale, garantisce un controllo preciso, consentendo movimenti fluidi e accurati nelle abbattitrici-raccoglitrici. Questa precisione facilita il funzionamento bidirezionale e la regolazione fine della velocit\u00e0, offrendo agli operatori un maggiore controllo durante le fasi di taglio e raccolta. Funzionalit\u00e0 integrate come i freni e i meccanismi di tripla riduzione migliorano ulteriormente la sicurezza e la reattivit\u00e0, garantendo una gestione affidabile in ambienti forestali dinamici e imprevedibili.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4660 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Gearbox-for-Feller-Bunchers.webp\" alt=\"Riduttore epicicloidale per abbattitrici-raccoglitrici\" width=\"1200\" height=\"750\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Gearbox-for-Feller-Bunchers.webp 1200w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Gearbox-for-Feller-Bunchers-980x613.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Gearbox-for-Feller-Bunchers-480x300.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/p>\n<h2>Applicazione del riduttore epicicloidale per trasmissione a cingolo<\/h2>\n<ul>\n<li><strong>Industria edile<\/strong><br \/>\nIl riduttore epicicloidale per cingoli \u00e8 ampiamente utilizzato nelle macchine edili come escavatori, bulldozer e pale caricatrici, che richiedono una trasmissione di coppia elevata per un funzionamento efficiente. Il suo design compatto garantisce una perfetta integrazione nei sistemi cingolati, consentendo prestazioni affidabili su terreni accidentati e in condizioni estreme. Riducendo i tempi di inattivit\u00e0 e gestendo carichi pesanti con precisione, aumenta significativamente la produttivit\u00e0 nei grandi progetti di costruzione e nelle operazioni di movimento terra, diventando un elemento fondamentale delle moderne attrezzature per l'edilizia.<\/li>\n<li><strong>Industria agricola<\/strong><br \/>\nNel settore agricolo, il riduttore epicicloidale alimenta trattori cingolati, mietitrebbie e raccoglitrici, garantendo una navigazione efficiente anche su terreni difficili come fango, suoli irregolari e residui colturali. La sua capacit\u00e0 di erogare un'elevata moltiplicazione della coppia e di resistere a fattori ambientali come polvere e umidit\u00e0 supporta operazioni essenziali come aratura, semina e raccolta. Questa durata ed efficienza contribuiscono ad aumentare la resa agricola, a ridurre il consumo di carburante e, in generale, al progresso delle moderne pratiche agricole.<\/li>\n<li><strong>Industria mineraria<\/strong><br \/>\nIl riduttore epicicloidale svolge un ruolo fondamentale nelle applicazioni minerarie, alimentando attrezzature come sistemi di trasporto, perforatrici e pale cingolate. Progettato per operare in ambienti difficili, eroga una coppia elevata per resistere a carichi d'urto e vibrazioni costanti nelle operazioni sotterranee o a cielo aperto. La sua struttura compatta ma robusta garantisce un'estrazione e un trasporto del materiale sicuri e continui, ottimizzando il recupero delle risorse, riducendo l'usura e prolungando la durata utile delle attrezzature minerarie in condizioni impegnative.<\/li>\n<li><strong>Industria forestale<\/strong><br \/>\nIl riduttore epicicloidale per la trasmissione del legname \u00e8 essenziale nelle macchine forestali come abbattitrici-raccoglitrici e mietitrici cingolate, consentendo un controllo preciso e una coppia elevata per il taglio, la raccolta e la manovrabilit\u00e0 in boschi fitti e su pendii ripidi. La sua struttura robusta e sigillata protegge da detriti, umidit\u00e0 e sbalzi di temperatura, garantendo un funzionamento ininterrotto anche negli ambienti forestali pi\u00f9 difficili. Questa affidabilit\u00e0 e prestazioni supportano pratiche di disboscamento sostenibili, riducendo al minimo le esigenze di manutenzione e rendendolo indispensabile per le moderne operazioni forestali.<\/li>\n<li><strong>Industria petrolifera e del gas<\/strong><br \/>\nNel settore petrolifero e del gas, il riduttore epicicloidale per la trasmissione su cingoli \u00e8 fondamentale per azionare piattaforme e attrezzature cingolate utilizzate nelle operazioni di perforazione, installazione di condotte e trasporto. La sua capacit\u00e0 di gestire coppie estreme e di operare in condizioni difficili, tra cui alte temperature e ambienti corrosivi, garantisce prestazioni affidabili. La durata e l'efficienza del riduttore riducono i tempi di inattivit\u00e0 e ottimizzano il consumo energetico, supportando operazioni critiche sia in applicazioni offshore che onshore, mantenendo al contempo la sicurezza e la continuit\u00e0 operativa.<\/li>\n<\/ul>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4573 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Loaders.webp\" alt=\"Trasmissione epicicloidale per caricatori\" width=\"900\" height=\"700\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Loaders.webp 900w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Loaders-480x373.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4571 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Cold-Planers.webp\" alt=\"Trasmissione planetaria per frese a freddo\" width=\"900\" height=\"700\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Cold-Planers.webp 900w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Cold-Planers-480x373.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>Trasmissione epicicloidale per caricatori<\/strong><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>Trasmissione planetaria per frese a freddo<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4593 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Harrows.webp\" alt=\"Trasmissione a cingoli planetari per erpici\" width=\"900\" height=\"700\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Harrows.webp 900w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Harrows-480x373.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4609 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Mulchers.webp\" alt=\"Trasmissione a cingoli planetari per trinciatrici\" width=\"900\" height=\"700\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Mulchers.webp 900w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Mulchers-480x373.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>Trasmissione a cingoli planetari per erpici<\/strong><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>Trasmissione a cingoli planetari per trinciatrici<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Risoluzione dei problemi del riduttore epicicloidale a trasmissione a cinghia<\/h2>\n<ul>\n<li><strong>Surriscaldamento durante il funzionamento<\/strong><br \/>\nIl surriscaldamento del riduttore epicicloidale \u00e8 spesso causato da lubrificazione insufficiente, carichi eccessivi o ostruzioni nei condotti di raffreddamento. Per risolvere questo problema, controllare i livelli di lubrificante e assicurarsi che l'olio soddisfi le specifiche del produttore. Pulire eventuali detriti che ostruiscono la ventilazione o i sistemi di raffreddamento e verificare la corretta dissipazione del calore. Se il problema persiste, controllare la presenza di disallineamenti o carichi operativi eccessivi. Sostituire le guarnizioni usurate o gli ingranaggi danneggiati per ripristinare le prestazioni termiche e prevenire guasti a lungo termine dei componenti durante applicazioni gravose.<\/li>\n<li><strong>Rumore e vibrazioni eccessivi<\/strong><br \/>\nUn rumore e delle vibrazioni eccessivi indicano in genere ingranaggi usurati o danneggiati, lubrificazione insufficiente o componenti planetari disallineati, tutti fattori che riducono l'efficienza e la durata. La risoluzione dei problemi prevede l'ispezione visiva e acustica del riduttore, la misurazione dei livelli di vibrazione con strumenti specializzati e il rabbocco o la sostituzione del lubrificante. Riallineare alberi e componenti, se necessario, per ridurre al minimo le irregolarit\u00e0. Se i problemi persistono, smontare il riduttore per ispezionare i denti degli ingranaggi alla ricerca di vaiolature o crepe e sostituire le parti difettose per garantire un funzionamento fluido e affidabile.<\/li>\n<li><strong>Perdite di lubrificante<\/strong><br \/>\nLe perdite di lubrificante nel cambio sono generalmente causate da guarnizioni deteriorate, carter incrinati o un montaggio errato, con conseguente contaminazione e riduzione della funzionalit\u00e0. Per individuare il problema, controllare tutte le guarnizioni e le tenute per verificare l'eventuale presenza di usura o danni e serrare i raccordi allentati. Eseguire una prova di pressione per identificare eventuali fratture nascoste nel carter. Pulire le aree interessate e applicare sigillanti o sostituire i componenti danneggiati, se necessario. Mantenere un adeguato livello di lubrificazione migliorer\u00e0 le prestazioni e prolungher\u00e0 la durata del cambio in condizioni difficili.<\/li>\n<li><strong>Usura dell'attrezzatura o punteggio<\/strong><br \/>\nL'usura o il danneggiamento degli ingranaggi sono spesso causati da contaminazione da detriti, sovraccarico o insufficiente indurimento del materiale, con conseguente riduzione della trasmissione della coppia e potenziali guasti. La risoluzione dei problemi richiede analisi periodiche dell'olio per rilevare la presenza di particelle, l'ispezione delle superfici degli ingranaggi con strumenti endoscopici per individuare irregolarit\u00e0 e il controllo dei carichi operativi per prevenire sollecitazioni eccessive. La rettifica degli ingranaggi leggermente danneggiati o la sostituzione completa di quelli gravemente usurati, unitamente a sistemi di filtrazione migliorati, contribuir\u00e0 a ridurre l'usura futura e a garantire un'affidabilit\u00e0 costante in applicazioni gravose.<\/li>\n<li><strong>Perdita di coppia o potenza<\/strong><br \/>\nLa perdita di coppia o di potenza pu\u00f2 derivare da slittamenti interni, guasti ai cuscinetti o inefficienze nei motori idraulici, riducendo la capacit\u00e0 del cambio di svolgere compiti gravosi. La risoluzione dei problemi prevede la verifica della coppia in uscita con un dinamometro, l'ispezione dei cuscinetti per individuare eventuali giochi, grippaggi o usura e la verifica delle fonti di alimentazione in ingresso per rilevare eventuali irregolarit\u00e0. Le azioni correttive includono la lubrificazione o la sostituzione dei cuscinetti, la ricalibrazione del sistema e la rimozione di eventuali ostruzioni nel percorso di trasmissione. Queste misure ripristineranno la piena capacit\u00e0 operativa e miglioreranno le prestazioni sotto carico.<\/li>\n<\/ul>\n<p dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4661 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Track-Drive-Planetary-Gearbox-for-Feller-Bunchers.webp\" alt=\"Riduttore epicicloidale a trazione cingolata per abbattitrici-raccoglitrici\" width=\"800\" height=\"800\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Track-Drive-Planetary-Gearbox-for-Feller-Bunchers.webp 800w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Track-Drive-Planetary-Gearbox-for-Feller-Bunchers-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Il riduttore epicicloidale per la trasmissione dei cingoli \u00e8 un sistema di trasmissione specializzato, parte integrante delle abbattitrici-raccoglitrici cingolate, macchine forestali pesanti progettate per il taglio e la raccolta di alberi in ambienti impervi. Questo riduttore epicicloidale per la trasmissione dei cingoli rappresenta un componente fondamentale del sottocarro, convertendo la potenza del motore in una coppia elevata per azionare i cingoli della macchina, consentendo una navigazione fluida su terreni irregolari, pendii ripidi e ostacoli comunemente incontrati nelle operazioni di disboscamento.<\/p>","protected":false},"featured_media":4509,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[195,194],"product_tag":[200,203,201,202,199,198,196,197],"class_list":{"0":"post-4658","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-planetary-track-drive","7":"product_cat-planetary-gearboxes","8":"product_tag-planetary-gear-reducers","9":"product_tag-planetary-gearbox-for-sale","10":"product_tag-planetary-gearbox-manufacturers","11":"product_tag-planetary-gearbox-suppliers","12":"product_tag-planetary-gearboxes","13":"product_tag-planetary-track-drive","14":"product_tag-planetary-track-drive-gearbox","15":"product_tag-track-drive-planetary-gearbox","17":"first","18":"instock","19":"shipping-taxable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/product\/4658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/comments?post=4658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/media\/4509"}],"wp:attachment":[{"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/media?parent=4658"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/product_brand?post=4658"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/product_cat?post=4658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/korea-transmission.com\/it\/wp-json\/wp\/v2\/product_tag?post=4658"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}