{"id":4646,"date":"2025-08-13T05:04:26","date_gmt":"2025-08-13T05:04:26","guid":{"rendered":"https:\/\/korea-transmission.com\/?post_type=product&#038;p=4646"},"modified":"2025-08-13T09:08:35","modified_gmt":"2025-08-13T09:08:35","slug":"planetary-track-drive-gearbox-for-crawler-cranes","status":"publish","type":"product","link":"https:\/\/korea-transmission.com\/es\/producto\/planetary-track-drive-gearbox-for-crawler-cranes\/","title":{"rendered":"Caja de engranajes de transmisi\u00f3n planetaria para gr\u00faas sobre orugas"},"content":{"rendered":"<p>La caja de engranajes planetarios para orugas es un sistema de transmisi\u00f3n especializado, esencial para las gr\u00faas sobre orugas. Est\u00e1 dise\u00f1ada para proporcionar una propulsi\u00f3n de alto par a los trenes de rodaje en entornos exigentes de construcci\u00f3n y elevaci\u00f3n de cargas pesadas. Funciona como un conjunto compacto de engranajes epic\u00edclicos que convierte la potencia de entrada de un motor hidr\u00e1ulico o el\u00e9ctrico en un par de salida amplificado, lo que permite a la gr\u00faa desplazarse por terrenos irregulares o blandos con estabilidad y eficiencia. Sus componentes clave incluyen un engranaje solar central, varios engranajes planetarios montados sobre un soporte, una corona dentada exterior y una carcasa robusta llena de aceite lubricante para minimizar la fricci\u00f3n y el desgaste.<\/p>\n<p>Este dise\u00f1o garantiza una distribuci\u00f3n uniforme de la carga en m\u00faltiples puntos de contacto de los engranajes, lo que mejora el rendimiento bajo cargas pesadas. Entre sus ventajas se incluyen una alta densidad de par para el manejo de pesos considerables, dimensiones compactas que reducen el tama\u00f1o y el peso total de la m\u00e1quina, una eficiencia mec\u00e1nica superior a la del 95% para optimizar el consumo de combustible y minimizar el calor, una durabilidad excepcional frente a cargas de choque y contaminantes como polvo o vibraciones, un funcionamiento silencioso adecuado para entornos urbanos y versatilidad para la personalizaci\u00f3n en diversos modelos de gr\u00faas. En las gr\u00faas sobre orugas, facilita la maniobrabilidad precisa durante las operaciones de elevaci\u00f3n, lo que contribuye a la fiabilidad operativa, la reducci\u00f3n del mantenimiento y el aumento de la productividad en industrias como la miner\u00eda, la construcci\u00f3n y el desarrollo de infraestructuras.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4505 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Crawler-Cranes.webp\" alt=\"Transmisi\u00f3n planetaria para gr\u00faas sobre orugas\" width=\"800\" height=\"800\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Crawler-Cranes.webp 800w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Crawler-Cranes-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<h2>Dimensiones de la transmisi\u00f3n por orugas planetarias<\/h2>\n<h3>EH 10000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4620 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1356\" height=\"748\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1.webp 1356w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1-1280x706.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1-980x541.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-1-480x265.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1356px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 94.62%; text-align: center;\" colspan=\"6\"><strong>Equipado con motor hidr\u00e1ulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 21.7653%; text-align: center;\" width=\"188\">VOAC F12-60<\/td>\n<td style=\"width: 7.19085%; text-align: center;\" width=\"178\">X = 146<\/td>\n<td style=\"width: 15.8459%; text-align: center;\" width=\"178\">VOAC F12-80<\/td>\n<td style=\"width: 23.94%; text-align: center;\" width=\"188\">X = 157<\/td>\n<td style=\"width: 10.6892%; text-align: center;\" width=\"178\">VOAC F12-110<\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\">X = 175<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 21.7653%; text-align: center;\" width=\"188\">SAUER 51C060<\/td>\n<td style=\"width: 7.19085%; text-align: center;\" width=\"178\">X = 207<\/td>\n<td style=\"width: 15.8459%; text-align: center;\" width=\"178\">SAUER 51C080<\/td>\n<td style=\"width: 23.94%; text-align: center;\" width=\"188\">X = 212<\/td>\n<td style=\"width: 10.6892%; text-align: center;\" width=\"178\">SAUER 51C110<\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\">X = 219<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 21.7653%; text-align: center;\" colspan=\"6\">Diferentes ejecuciones de entrada disponibles bajo demanda.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"height: 240px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 88.4489%; text-align: center;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\" width=\"136\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 24.0351%; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 11.7773%; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 11.2419%; text-align: center;\" width=\"146\">Cantidad de aceite<\/td>\n<td style=\"width: 11.1081%; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 7.3742%; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 10.5996%; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 13.4422%; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 10.5929%; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 11.7773%; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 11.2419%; text-align: center;\" width=\"146\">[ litros ]<\/td>\n<td style=\"width: 11.1081%; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 7.3742%; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 10.5996%; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\">100000<\/td>\n<td style=\"width: 13.4422%; text-align: center;\">512<\/td>\n<td style=\"width: 10.5929%; text-align: center;\">1080<\/td>\n<td style=\"width: 11.7773%; text-align: center;\">410<\/td>\n<td style=\"width: 11.2419%; text-align: center;\">6.5<\/td>\n<td style=\"width: 11.1081%; text-align: center;\" width=\"136\">1500\u00f7460<\/td>\n<td style=\"width: 7.3742%; text-align: center;\" width=\"136\">42\u00f717<\/td>\n<td style=\"width: 10.5996%; text-align: center;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 88.4489%; text-align: center;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\">76.1<\/td>\n<td style=\"width: 13.4422%; text-align: center;\">86<\/td>\n<td style=\"width: 10.5929%; text-align: center;\">101.3<\/td>\n<td style=\"width: 11.7773%; text-align: center;\">114.4<\/td>\n<td style=\"width: 11.2419%; text-align: center;\">124.2<\/td>\n<td style=\"width: 11.1081%; text-align: center;\">132.4<\/td>\n<td style=\"width: 7.3742%; text-align: center;\">140.2<\/td>\n<td style=\"width: 10.5996%; text-align: center;\">153.9<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 12.3127%; text-align: center;\">173.7<\/td>\n<td style=\"width: 13.4422%; text-align: center;\">185.4<\/td>\n<td style=\"width: 10.5929%; text-align: center;\" colspan=\"6\">209.3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>PISTA EH 13000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4621 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1381\" height=\"753\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2.webp 1381w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2-1280x698.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2-980x534.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-2-480x262.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1381px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 98.469%; text-align: center;\" colspan=\"6\"><strong>Equipado con motor hidr\u00e1ulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.0193%; text-align: center;\" width=\"188\">VOAC F12-80<\/td>\n<td style=\"width: 7.60171%; text-align: center;\" width=\"178\">X = 157<\/td>\n<td style=\"width: 16.7024%; text-align: center;\" width=\"188\">VOAC F12-110<\/td>\n<td style=\"width: 22.1628%; text-align: center;\" width=\"544\">X = 175<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.0193%; text-align: center;\" width=\"188\">SAUER 51C080<\/td>\n<td style=\"width: 7.60171%; text-align: center;\" width=\"178\">X = 212<\/td>\n<td style=\"width: 16.7024%; text-align: center;\" width=\"188\">SAUER 51C110<\/td>\n<td style=\"width: 22.1628%; text-align: center;\" width=\"178\">X = 219<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\">SAUER 51C160<\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\">X = 240<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 98.469%; text-align: center;\" colspan=\"6\">Diferentes ejecuciones de entrada disponibles bajo demanda.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"height: 240px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.9999%; text-align: center;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 27.1948%; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 11.9914%; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 13.2762%; text-align: center;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 12.5268%; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 8.35118%; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 15.2034%; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 11.9914%; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 11.9914%; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 13.2762%; text-align: center;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 12.5268%; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 8.35118%; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\">150000<\/td>\n<td style=\"width: 15.2034%; text-align: center;\">512<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">1080<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">440<\/td>\n<td style=\"width: 13.2762%; text-align: center;\">7.5<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">2200\u00f7650<\/td>\n<td style=\"width: 12.5268%; text-align: center;\" width=\"136\">42\u00f717<\/td>\n<td style=\"width: 8.35118%; text-align: center;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.9999%; text-align: center;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\">76.1<\/td>\n<td style=\"width: 15.2034%; text-align: center;\">86<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">101.3<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">114.4<\/td>\n<td style=\"width: 13.2762%; text-align: center;\">124.2<\/td>\n<td style=\"width: 12.7409%; text-align: center;\">131<\/td>\n<td style=\"width: 12.5268%; text-align: center;\">140.2<\/td>\n<td style=\"width: 8.35118%; text-align: center;\">149<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.9186%; text-align: center;\">168.1<\/td>\n<td style=\"width: 15.2034%; text-align: center;\">175.3<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">197.8<\/td>\n<td style=\"width: 11.9914%; text-align: center;\">214.8<\/td>\n<td style=\"width: 13.2762%; text-align: center;\">242.3<\/td>\n<td style=\"width: 12.7409%; text-align: center;\"><\/td>\n<td style=\"width: 12.5268%; text-align: center;\"><\/td>\n<td style=\"width: 8.35118%; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 16000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4622 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1414\" height=\"779\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3.webp 1414w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3-1280x705.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3-980x540.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-3-480x264.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1414px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.4325%; text-align: center;\" colspan=\"6\"><strong>Equipado con motor hidr\u00e1ulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.3405%; text-align: center;\" width=\"178\">VOAC F12-110<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"188\">X = 175<\/td>\n<td style=\"width: 16.9165%; text-align: center;\" width=\"178\">VOAC F11-150 CETOP<\/td>\n<td style=\"width: 22.4839%; text-align: center;\" width=\"188\">X = 307<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.3405%; text-align: center;\" width=\"178\">SAUER 51C110<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"188\">X = 219<\/td>\n<td style=\"width: 16.9165%; text-align: center;\" width=\"178\">SAUER 51C160<\/td>\n<td style=\"width: 22.4839%; text-align: center;\" width=\"544\">X = 240<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.4325%; text-align: center;\" colspan=\"6\">Diferentes ejecuciones de entrada disponibles bajo demanda.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 934px; text-align: center;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 254px; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 124px; text-align: center;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 78px; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 142px; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 124px; text-align: center;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 78px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">170000<\/td>\n<td style=\"width: 142px; text-align: center;\">765<\/td>\n<td style=\"width: 112px; text-align: center;\">1660<\/td>\n<td style=\"width: 112px; text-align: center;\">680<\/td>\n<td style=\"width: 124px; text-align: center;\">11.5<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">2200\u00f7700<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">50\u00f720<\/td>\n<td style=\"width: 78px; text-align: center;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 934px; text-align: center;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">85.2<\/td>\n<td style=\"width: 142px; text-align: center;\">96.2<\/td>\n<td style=\"width: 112px; text-align: center;\">109.2<\/td>\n<td style=\"width: 112px; text-align: center;\">123.2<\/td>\n<td style=\"width: 124px; text-align: center;\">141.7<\/td>\n<td style=\"width: 119px; text-align: center;\">160<\/td>\n<td style=\"width: 117px; text-align: center;\">182.1<\/td>\n<td style=\"width: 78px; text-align: center;\">188.4<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">212.6<\/td>\n<td style=\"width: 142px; text-align: center;\">227.8<\/td>\n<td style=\"width: 112px; text-align: center;\">257.1<\/td>\n<td style=\"width: 112px; text-align: center;\"><\/td>\n<td style=\"width: 124px; text-align: center;\"><\/td>\n<td style=\"width: 119px; text-align: center;\"><\/td>\n<td style=\"width: 117px; text-align: center;\"><\/td>\n<td style=\"width: 78px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 22000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4623 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1444\" height=\"788\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4.webp 1444w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4-1280x699.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4-980x535.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-4-480x262.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1444px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Equipado con motor hidr\u00e1ulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"188\">VOAC F11-150 CETOP<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"178\">X = 307<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\">VOAC F11-250<\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\">X = 431<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"188\">SAUER 51C160<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"178\">X = 239<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\">SAUER 51V250<\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\">X = 460<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Diferentes ejecuciones de entrada disponibles bajo demanda.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 934px; text-align: center;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 254px; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 124px; text-align: center;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 78px; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 142px; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 112px; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 124px; text-align: center;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 78px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">240000<\/td>\n<td style=\"width: 142px; text-align: center;\">765<\/td>\n<td style=\"width: 112px; text-align: center;\">1660<\/td>\n<td style=\"width: 112px; text-align: center;\">880<\/td>\n<td style=\"width: 124px; text-align: center;\">15<\/td>\n<td style=\"width: 119px; text-align: center;\" width=\"146\">2350\u00f7950<\/td>\n<td style=\"width: 117px; text-align: center;\" width=\"136\">50\u00f720<\/td>\n<td style=\"width: 78px; text-align: center;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 934px; text-align: center;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">86.6<\/td>\n<td style=\"width: 142px; text-align: center;\">97.6<\/td>\n<td style=\"width: 112px; text-align: center;\">112.6<\/td>\n<td style=\"width: 112px; text-align: center;\">127.1<\/td>\n<td style=\"width: 124px; text-align: center;\">142.7<\/td>\n<td style=\"width: 119px; text-align: center;\">151.9<\/td>\n<td style=\"width: 117px; text-align: center;\">161.1<\/td>\n<td style=\"width: 78px; text-align: center;\">168.1<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 130px; text-align: center;\">182.3<\/td>\n<td style=\"width: 142px; text-align: center;\">211<\/td>\n<td style=\"width: 112px; text-align: center;\">223.3<\/td>\n<td style=\"width: 112px; text-align: center;\">252<\/td>\n<td style=\"width: 124px; text-align: center;\"><\/td>\n<td style=\"width: 119px; text-align: center;\"><\/td>\n<td style=\"width: 117px; text-align: center;\"><\/td>\n<td style=\"width: 78px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 26000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4624 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1438\" height=\"774\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5.webp 1438w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5-1280x689.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5-980x527.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-5-480x258.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1438px, 100vw\" \/><\/p>\n<table style=\"height: 140px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Equipado con motor hidr\u00e1ulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 23.4475%;\" width=\"178\">VOAC F11-250<\/td>\n<td style=\"text-align: center; width: 7.70878%;\" width=\"910\">X = 431<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 23.4475%;\" width=\"178\">SAUER 51V250<\/td>\n<td style=\"text-align: center; width: 7.70878%;\" width=\"188\">X = 460<\/td>\n<td style=\"text-align: center; width: 17.0236%;\" width=\"178\">SAUER 51C160<\/td>\n<td style=\"text-align: center; width: 22.591%;\" width=\"544\">X = 239<\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Diferentes ejecuciones de entrada disponibles bajo demanda.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7858%; text-align: center;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.3833%; text-align: center;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 26.0171%; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 11.4561%; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 14.0257%; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 13.9186%; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 8.24411%; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.3833%; text-align: center;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 14.561%; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 11.4561%; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 11.4561%; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 12.7409%; text-align: center;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 14.0257%; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 13.9186%; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 8.24411%; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 13.3833%;\">280000<\/td>\n<td style=\"text-align: center; width: 14.561%;\">1080<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">2360<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">980<\/td>\n<td style=\"text-align: center; width: 12.7409%;\">18<\/td>\n<td style=\"text-align: center; width: 14.0257%;\" width=\"136\">2500\u00f71100<\/td>\n<td style=\"text-align: center; width: 13.9186%;\" width=\"136\">50\u00f720<\/td>\n<td style=\"text-align: center; width: 8.24411%;\">300<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7858%; text-align: center;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 13.3833%;\">86.6<\/td>\n<td style=\"text-align: center; width: 14.561%;\">97.6<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">112.6<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">127.1<\/td>\n<td style=\"text-align: center; width: 12.7409%;\">142.7<\/td>\n<td style=\"text-align: center; width: 14.0257%;\">151.9<\/td>\n<td style=\"text-align: center; width: 13.9186%;\">161.1<\/td>\n<td style=\"text-align: center; width: 8.24411%;\">168.1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; width: 13.3833%;\">182.3<\/td>\n<td style=\"text-align: center; width: 14.561%;\">211<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">223.3<\/td>\n<td style=\"text-align: center; width: 11.4561%;\">252<\/td>\n<td style=\"width: 12.7409%; text-align: center;\"><\/td>\n<td style=\"width: 14.0257%; text-align: center;\"><\/td>\n<td style=\"width: 13.9186%; text-align: center;\"><\/td>\n<td style=\"width: 8.24411%; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 33000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4625 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1463\" height=\"783\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6.webp 1463w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6-1280x685.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6-980x524.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-6-480x257.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1463px, 100vw\" \/><\/p>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Equipado con motor hidr\u00e1ulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"178\">VOAC F11-250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"910\">X = 431<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"178\">SAUER 51V250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"188\">X = 460<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"544\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Diferentes ejecuciones de entrada disponibles bajo demanda.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse; height: 185px;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; text-align: center; height: 23px;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 13.3833%; text-align: center; height: 47px;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 26.0171%; text-align: center; height: 47px;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 11.4561%; text-align: center; height: 47px;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 12.7409%; text-align: center; height: 47px;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 14.0257%; text-align: center; height: 47px;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 13.9186%; text-align: center; height: 47px;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 8.24411%; text-align: center; height: 47px;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; text-align: center; height: 23px;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 14.561%; text-align: center; height: 23px;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 11.4561%; text-align: center; height: 23px;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 11.4561%; text-align: center; height: 23px;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 12.7409%; text-align: center; height: 23px;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 14.0257%; text-align: center; height: 23px;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 13.9186%; text-align: center; height: 23px;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 8.24411%; text-align: center; height: 23px;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr style=\"height: 13.75pt;\">\n<td class=\"et27\" style=\"text-align: center; width: 13.3833%;\">350000<\/td>\n<td class=\"et28\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 14.561%;\">1120<\/td>\n<td class=\"et28\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 11.4561%;\">2550<\/td>\n<td class=\"et44\" style=\"text-align: center; width: 11.4561%;\">1280<\/td>\n<td class=\"et44\" style=\"text-align: center; width: 12.7409%;\">21<\/td>\n<td class=\"et45\" style=\"width: 14.0257%; border-right: 0.5pt solid #d1d3d4; text-align: center;\" width=\"136\"><span class=\"font3\">3550\u00f71350<\/span><\/td>\n<td class=\"et47\" style=\"width: 13.9186%; border-right: 0.5pt solid #d1d3d4; text-align: center;\" width=\"146\"><span class=\"font3\">40\u00f720<\/span><\/td>\n<td class=\"et28\" style=\"text-align: center; width: 8.24411%;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; text-align: center; height: 23px;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 14.00pt;\">\n<td class=\"et32\" style=\"text-align: center; width: 13.3833%;\">86.6<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 14.561%;\">97.6<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 11.4561%;\">112.6<\/td>\n<td class=\"et49\" style=\"text-align: center; width: 11.4561%;\">127.1<\/td>\n<td class=\"et49\" style=\"text-align: center; width: 12.7409%;\">142.7<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 14.0257%;\">151.9<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 13.9186%;\">161.1<\/td>\n<td class=\"et33\" style=\"text-align: center; width: 8.24411%;\">182.3<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et27\" style=\"text-align: center; width: 13.3833%;\">211<\/td>\n<td class=\"et33\" style=\"border-right: 0.5pt solid #d1d3d4; text-align: center; width: 14.561%;\">223.3<\/td>\n<td class=\"et35\" style=\"text-align: center; width: 11.4561%;\">252<\/td>\n<td style=\"text-align: center; width: 11.4561%; height: 23px;\"><\/td>\n<td style=\"width: 12.7409%; text-align: center; height: 23px;\"><\/td>\n<td style=\"width: 14.0257%; text-align: center; height: 23px;\"><\/td>\n<td style=\"width: 13.9186%; text-align: center; height: 23px;\"><\/td>\n<td style=\"width: 8.24411%; text-align: center; height: 23px;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 33000 W<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4626 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1464\" height=\"797\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7.webp 1464w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7-1280x697.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7-980x534.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-7-480x261.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1464px, 100vw\" \/><\/p>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Equipado con motor hidr\u00e1ulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"178\">VOAC F11-250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"910\">X = 431<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"178\">SAUER 51V250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"188\">X = 460<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"544\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Diferentes ejecuciones de entrada disponibles bajo demanda.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"height: 189px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 13.3833%; height: 47px; text-align: center;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 26.0171%; height: 47px; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 11.4561%; height: 47px; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 12.7409%; height: 47px; text-align: center;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 14.0257%; height: 47px; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 13.9186%; height: 47px; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 8.24411%; height: 47px; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\">350000<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\">1120<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">2550<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">1280<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\">25<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">3550\u00f71350<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">40\u00f720<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 27px;\">\n<td style=\"width: 13.3833%; height: 27px; text-align: center;\">86.6<\/td>\n<td style=\"width: 14.561%; height: 27px; text-align: center;\">97.6<\/td>\n<td style=\"width: 11.4561%; height: 27px; text-align: center;\">112.6<\/td>\n<td style=\"width: 11.4561%; height: 27px; text-align: center;\">127.1<\/td>\n<td style=\"width: 12.7409%; height: 27px; text-align: center;\">142.7<\/td>\n<td style=\"width: 14.0257%; height: 27px; text-align: center;\">151.9<\/td>\n<td style=\"width: 13.9186%; height: 27px; text-align: center;\">161.1<\/td>\n<td style=\"width: 8.24411%; height: 27px; text-align: center;\">182.3<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 13.3833%; text-align: center;\">211<\/td>\n<td style=\"width: 14.561%; text-align: center;\">223.3<\/td>\n<td style=\"width: 11.4561%; text-align: center;\">252<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 45000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4627 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1443\" height=\"793\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8.webp 1443w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8-1280x703.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8-980x539.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-8-480x264.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1443px, 100vw\" \/><\/p>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\"><strong>Equipado con motor hidr\u00e1ulico<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"188\">VOAC F11-250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"178\">X = 431<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"554\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"188\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 23.4475%; text-align: center;\" width=\"188\">SAUER 51V250<\/td>\n<td style=\"width: 7.70878%; text-align: center;\" width=\"178\">X = 460<\/td>\n<td style=\"width: 17.0236%; text-align: center;\" width=\"178\"><\/td>\n<td style=\"width: 22.591%; text-align: center;\" width=\"544\"><\/td>\n<td style=\"width: 13.7941%; text-align: center;\" width=\"188\"><\/td>\n<td style=\"width: 15.1887%; text-align: center;\" width=\"178\"><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 99.7537%; text-align: center;\" colspan=\"6\">Diferentes ejecuciones de entrada disponibles bajo demanda.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"height: 185px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 13.3833%; height: 47px; text-align: center;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 26.0171%; height: 47px; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 11.4561%; height: 47px; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 12.7409%; height: 47px; text-align: center;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 14.0257%; height: 47px; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 13.9186%; height: 47px; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 8.24411%; height: 47px; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\">450000<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\">1120<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">2550<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">1560<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\">24<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">3750\u00f71500<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">40\u00f720<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\">85.2<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\">95.9<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">110.7<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\">132.3<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\">140.3<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\">158.8<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\">183.8<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\">219.6<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 60000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4628 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1432\" height=\"796\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9.webp 1432w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9-1280x712.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9-980x545.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-9-480x267.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1432px, 100vw\" \/><\/p>\n<table style=\"height: 185px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Dimensi\u00f3n de salida<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 13.3833%; height: 47px; text-align: center;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 26.0171%; height: 47px; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 11.4561%; height: 47px; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 12.7409%; height: 47px; text-align: center;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 14.0257%; height: 47px; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 13.9186%; height: 47px; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 8.24411%; height: 47px; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 13.3833%; height: 23px; text-align: center;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 14.561%; height: 23px; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr style=\"height: 13.75pt;\">\n<td class=\"et11\" style=\"width: 13.3833%; text-align: center;\">685000<\/td>\n<td class=\"et12\" style=\"width: 14.561%; text-align: center;\">1380<\/td>\n<td class=\"et12\" style=\"width: 11.4561%; text-align: center;\">3050<\/td>\n<td class=\"et12\" style=\"width: 11.4561%; text-align: center;\">3120<\/td>\n<td class=\"et12\" style=\"width: 12.7409%; text-align: center;\">50<\/td>\n<td class=\"et13\" style=\"width: 14.0257%; text-align: center;\" width=\"136\"><span class=\"font3\">4000\u00f71300<\/span><\/td>\n<td class=\"et13\" style=\"width: 13.9186%; text-align: center;\" width=\"136\"><span class=\"font3\">30\u00f720<\/span><\/td>\n<td class=\"et23\" style=\"width: 8.24411%; text-align: center;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 99.7858%; height: 23px; text-align: center;\" colspan=\"8\"><strong>Relaci\u00f3n de reducci\u00f3n efectiva<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 14.50pt;\">\n<td class=\"et16\" style=\"width: 13.3833%; text-align: center;\">330.7<\/td>\n<td class=\"et17\" style=\"width: 14.561%; text-align: center;\">373.1<\/td>\n<td class=\"et18\" style=\"width: 11.4561%; text-align: center;\">442.3<\/td>\n<td style=\"width: 11.4561%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 12.7409%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 14.0257%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 13.9186%; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 8.24411%; height: 23px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>EH 70000 SC<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4629 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10.webp\" alt=\"Dimensiones de la transmisi\u00f3n por orugas planetarias\" width=\"1395\" height=\"793\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10.webp 1395w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10-1280x728.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10-980x557.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Dimensions-10-480x273.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1395px, 100vw\" \/><\/p>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 932px; height: 23px; text-align: center;\" colspan=\"8\">Dimensi\u00f3n de salida<\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td style=\"width: 125px; height: 47px; text-align: center;\" width=\"146\">Par m\u00e1ximo de salida<\/td>\n<td style=\"width: 243px; height: 47px; text-align: center;\" colspan=\"2\" width=\"272\">Capacidad de los rodamientos<\/td>\n<td style=\"width: 107px; height: 47px; text-align: center;\" width=\"136\">Peso sin motor<\/td>\n<td style=\"width: 119px; height: 47px; text-align: center;\" width=\"136\">Cantidad de aceite<\/td>\n<td style=\"width: 131px; height: 47px; text-align: center;\" width=\"136\">Par de frenado<\/td>\n<td style=\"width: 130px; height: 47px; text-align: center;\" width=\"136\">Presi\u00f3n de apertura<\/td>\n<td style=\"width: 77px; height: 47px; text-align: center;\" width=\"136\">Presi\u00f3n m\u00e1xima de freno<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 125px; height: 23px; text-align: center;\" width=\"146\">[ Nm ]<\/td>\n<td style=\"width: 136px; height: 23px; text-align: center;\" width=\"136\">Cd din\u00e1mico [kN]<\/td>\n<td style=\"width: 107px; height: 23px; text-align: center;\" width=\"136\">C0 est\u00e1tico [ kN ]<\/td>\n<td style=\"width: 107px; height: 23px; text-align: center;\" width=\"136\">[ kilos ]<\/td>\n<td style=\"width: 119px; height: 23px; text-align: center;\" width=\"136\">[ litros ]<\/td>\n<td style=\"width: 131px; height: 23px; text-align: center;\" width=\"136\">[ Nm ]<\/td>\n<td style=\"width: 130px; height: 23px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<td style=\"width: 77px; height: 23px; text-align: center;\" width=\"136\">[ bar ]<\/td>\n<\/tr>\n<tr style=\"height: 13.75pt;\">\n<td class=\"et10\" style=\"width: 125px; text-align: center;\">865000<\/td>\n<td class=\"et11\" style=\"width: 136px; text-align: center;\">1380<\/td>\n<td class=\"et11\" style=\"width: 107px; text-align: center;\">3050<\/td>\n<td class=\"et11\" style=\"width: 107px; text-align: center;\">3120<\/td>\n<td class=\"et11\" style=\"width: 119px; text-align: center;\">50<\/td>\n<td class=\"et12\" style=\"width: 131px; text-align: center;\" width=\"136\"><span class=\"font3\">4000\u00f71700<\/span><\/td>\n<td class=\"et12\" style=\"width: 130px; text-align: center;\" width=\"136\"><span class=\"font3\">30\u00f720<\/span><\/td>\n<td class=\"et22\" style=\"width: 77px; text-align: center;\">300<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 932px; height: 23px; text-align: center;\" colspan=\"8\">Relaci\u00f3n de reducci\u00f3n efectiva<\/td>\n<\/tr>\n<tr style=\"height: 13.75pt;\">\n<td class=\"et10\" style=\"width: 125px; text-align: center;\">287<\/td>\n<td class=\"et15\" style=\"width: 136px; text-align: center;\">323.8<\/td>\n<td class=\"et15\" style=\"width: 107px; text-align: center;\">368.6<\/td>\n<td class=\"et15\" style=\"width: 107px; text-align: center;\">415.8<\/td>\n<td class=\"et15\" style=\"width: 119px; text-align: center;\">437.7<\/td>\n<td class=\"et16\" style=\"width: 131px; text-align: center;\">493.7<\/td>\n<td style=\"width: 130px; height: 23px; text-align: center;\"><\/td>\n<td style=\"width: 77px; height: 23px; text-align: center;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Caracter\u00edsticas de la caja de engranajes de transmisi\u00f3n planetaria de la gr\u00faa sobre orugas<\/h2>\n<p><strong>1. Dise\u00f1o compacto y que ahorra espacio<\/strong><br \/>\nLa caja de engranajes de transmisi\u00f3n planetaria presenta un dise\u00f1o compacto y eficiente que se integra a la perfecci\u00f3n en el tren de rodaje de la gr\u00faa. Esta configuraci\u00f3n, que ahorra espacio, reduce las dimensiones generales de la m\u00e1quina, mejora su transportabilidad y aumenta la estabilidad sin sacrificar el rendimiento. Su dise\u00f1o de bajo perfil garantiza una excelente maniobrabilidad, especialmente en obras con espacio reducido, lo que la hace ideal para entornos exigentes.<\/p>\n<p><strong>2. Alta densidad de par<\/strong><br \/>\nDise\u00f1ada para ofrecer un alto par motor, la caja de engranajes planetarios convierte eficientemente la potencia de entrada de los motores hidr\u00e1ulicos o el\u00e9ctricos en un par amplificado. La configuraci\u00f3n de engranajes planetarios multietapa distribuye uniformemente las fuerzas entre los distintos engranajes, garantizando un rendimiento \u00f3ptimo bajo cargas pesadas y minimizando el desgaste. Esta capacidad permite a las gr\u00faas sobre orugas desplazarse por terrenos dif\u00edciles y manipular cargas considerables con precisi\u00f3n y fiabilidad.<\/p>\n<p><strong>3. Construcci\u00f3n robusta y durabilidad<\/strong><br \/>\nDise\u00f1ada para soportar entornos adversos, la caja de engranajes planetarios de transmisi\u00f3n por orugas cuenta con carcasas reforzadas y rodamientos de complemento completo que absorben las fuerzas axiales y radiales. Esta robusta construcci\u00f3n resiste golpes, vibraciones y contaminantes como el polvo y la humedad, garantizando una fiabilidad a largo plazo. Su durabilidad minimiza el tiempo de inactividad y prolonga la vida \u00fatil en aplicaciones exigentes como la miner\u00eda, la infraestructura y la construcci\u00f3n pesada.<\/p>\n<p><strong>4. Eficiencia mec\u00e1nica excepcional<\/strong><br \/>\nEl avanzado sistema de engranajes planetarios logra una eficiencia mec\u00e1nica superior a 95%, optimizando el consumo de energ\u00eda y reduciendo la generaci\u00f3n de calor durante el funcionamiento. Esta eficiencia contribuye al ahorro de combustible, disminuye los costos operativos y minimiza el impacto ambiental, lo que lo hace id\u00f3neo para tareas de elevaci\u00f3n y movimiento prolongadas en aplicaciones profesionales.<\/p>\n<p><strong>5. Alta capacidad de carga<\/strong><br \/>\nGracias a sus componentes reforzados y robustos sistemas de rodamientos, el reductor de engranajes planetarios para orugas soporta las cargas radiales y axiales propias de las gr\u00faas sobre orugas. Esta elevada capacidad de carga garantiza una propulsi\u00f3n estable incluso en superficies irregulares, mejorando la seguridad, la precisi\u00f3n y la fiabilidad durante las operaciones de elevaci\u00f3n de gran envergadura en entornos industriales y de construcci\u00f3n.<\/p>\n<p><strong>6. Versatilidad y opciones de personalizaci\u00f3n<\/strong><br \/>\nEl sistema de transmisi\u00f3n planetaria es altamente vers\u00e1til y compatible con frenos, pi\u00f1ones y diversos tipos de motores. Su adaptabilidad permite soluciones personalizadas para cada modelo de gr\u00faa sobre orugas y terreno, garantizando flexibilidad operativa. Esta caracter\u00edstica simplifica el mantenimiento, aumenta la productividad y asegura una integraci\u00f3n perfecta con los sistemas hidr\u00e1ulicos modernos en diversas obras de construcci\u00f3n a nivel mundial.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4648 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Gearbox-for-Crawler-Cranes.webp\" alt=\"Caja de engranajes de transmisi\u00f3n planetaria para gr\u00faas sobre orugas\" width=\"1200\" height=\"760\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Gearbox-for-Crawler-Cranes.webp 1200w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Gearbox-for-Crawler-Cranes-980x621.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-Gearbox-for-Crawler-Cranes-480x304.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/p>\n<h2>Aplicaciones de las cajas de engranajes planetarios de transmisi\u00f3n por orugas<\/h2>\n<p><strong>1. Industria de la construcci\u00f3n<\/strong><br \/>\nEn el sector de la construcci\u00f3n, las cajas de engranajes planetarios para orugas son esenciales para gr\u00faas sobre orugas, excavadoras y veh\u00edculos de orugas. Permiten maniobras precisas, un alto par motor y estabilidad, garantizando operaciones eficientes en terrenos irregulares. Estas cajas de engranajes mejoran la productividad en tareas como el izamiento de cargas pesadas, la preparaci\u00f3n del terreno y los trabajos de cimentaci\u00f3n, lo que las convierte en indispensables para el desarrollo de infraestructuras.<\/p>\n<p><strong>2. Industria agr\u00edcola<\/strong><br \/>\nLas cajas de engranajes planetarios desempe\u00f1an un papel fundamental en la maquinaria agr\u00edcola, como los tractores de orugas y las cosechadoras. Su alto par motor y durabilidad permiten un funcionamiento eficaz en terrenos blandos o irregulares. Estas cajas de engranajes garantizan una propulsi\u00f3n y un rendimiento fiables durante el arado, la siembra y la cosecha, optimizando la eficiencia energ\u00e9tica y reduciendo el desgaste en entornos agr\u00edcolas exigentes.<\/p>\n<p><strong>3. Industria forestal<\/strong><br \/>\nEn aplicaciones forestales, las cajas de engranajes planetarios para la transmisi\u00f3n de orugas se utilizan en equipos de tala, transportadores de orugas y cosechadoras de \u00e1rboles. Proporcionan el par motor y la durabilidad necesarios para sortear terrenos dif\u00edciles y manejar cargas pesadas, como \u00e1rboles talados. Su robusta construcci\u00f3n garantiza un rendimiento fiable incluso en condiciones adversas, minimizando el tiempo de inactividad y aumentando la eficiencia operativa.<\/p>\n<p><strong>4. Industria minera<\/strong><br \/>\nLos equipos de miner\u00eda, como las perforadoras sobre orugas y los sistemas de transporte sobre orugas, dependen de los engranajes planetarios para lograr una alta capacidad de carga y una elevada densidad de par. Estas cajas de engranajes est\u00e1n dise\u00f1adas para soportar condiciones extremas, como fuertes vibraciones, polvo e impactos, lo que garantiza operaciones eficientes de manipulaci\u00f3n, excavaci\u00f3n y transporte de materiales en minas profundas o a cielo abierto.<\/p>\n<p><strong>5. Industria del petr\u00f3leo y el gas<\/strong><br \/>\nLos reductores de engranajes planetarios para orugas son esenciales en la exploraci\u00f3n y producci\u00f3n de petr\u00f3leo y gas, ya que impulsan plataformas de perforaci\u00f3n y sistemas de transporte sobre orugas. Su capacidad para operar con alta eficiencia bajo cargas pesadas y en terrenos dif\u00edciles garantiza el movimiento fiable de los equipos de perforaci\u00f3n. Adem\u00e1s, son resistentes a entornos adversos, incluyendo la exposici\u00f3n al petr\u00f3leo, al lodo y a temperaturas extremas.<\/p>\n<p><strong>6. Industria mar\u00edtima<\/strong><br \/>\nEn la industria naval, las cajas de engranajes planetarios para orugas se utilizan habitualmente en veh\u00edculos marinos anfibios y de orugas. Su dise\u00f1o compacto y su alto par motor les permiten operar con eficiencia tanto en tierra como en agua. Estas cajas de engranajes garantizan una propulsi\u00f3n estable, durabilidad en entornos corrosivos y un rendimiento fiable en aplicaciones como el dragado, la restauraci\u00f3n de playas y la construcci\u00f3n en alta mar.<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4573 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Loaders.webp\" alt=\"Transmisi\u00f3n planetaria de cadenas para cargadoras\" width=\"900\" height=\"700\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Loaders.webp 900w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Loaders-480x373.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4595 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Planters.webp\" alt=\"Sistema de transmisi\u00f3n planetaria para sembradoras\" width=\"900\" height=\"700\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Planters.webp 900w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Planters-480x373.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>Transmisi\u00f3n planetaria de cadenas para cargadoras<\/strong><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>Sistema de transmisi\u00f3n planetaria para sembradoras<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4572 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Excavators.webp\" alt=\"Transmisi\u00f3n planetaria de cadenas para excavadoras\" width=\"900\" height=\"700\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Excavators.webp 900w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Excavators-480x373.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4609 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Mulchers.webp\" alt=\"Transmisi\u00f3n planetaria de orugas para trituradoras\" width=\"900\" height=\"700\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Mulchers.webp 900w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/0_Planetary-Track-Drive-for-Mulchers-480x373.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 900px, 100vw\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>Transmisi\u00f3n planetaria de cadenas para excavadoras<\/strong><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>Transmisi\u00f3n planetaria de orugas para trituradoras<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Elija el sistema de transmisi\u00f3n planetaria adecuado para gr\u00faas sobre orugas.<\/h2>\n<p><strong>1. Determinar los requisitos de par<\/strong><br \/>\nComience calculando el par m\u00e1ximo necesario en funci\u00f3n de la capacidad de carga de la gr\u00faa y el terreno de operaci\u00f3n. Considere la distribuci\u00f3n del peso y las fuerzas din\u00e1micas para asegurar que la caja de engranajes se ajuste a las necesidades de la gr\u00faa. Una selecci\u00f3n adecuada del par evita la sobrecarga, maximiza el rendimiento y garantiza un funcionamiento fiable durante el izaje de cargas pesadas en entornos dif\u00edciles, prolongando as\u00ed la vida \u00fatil de la caja de engranajes.<\/p>\n<p><strong>2. Evaluar el \u00edndice de reducci\u00f3n<\/strong><br \/>\nSeleccione una caja de engranajes planetarios con una relaci\u00f3n de reducci\u00f3n adecuada que se ajuste a la velocidad de la gr\u00faa y a la potencia de entrada de los motores hidr\u00e1ulicos o el\u00e9ctricos. Las configuraciones planetarias multietapa proporcionan una multiplicaci\u00f3n de par \u00f3ptima para movimientos lentos y controlados. Esto garantiza un funcionamiento eficiente, evita la sobrecarga y mejora la maniobrabilidad en terrenos irregulares o blandos, lo cual es fundamental para la precisi\u00f3n durante las tareas de elevaci\u00f3n o transporte.<\/p>\n<p><strong>3. Priorizar la durabilidad y la construcci\u00f3n robusta.<\/strong><br \/>\nOpte por una caja de engranajes para orugas fabricada con materiales resistentes a condiciones adversas, como polvo, vibraciones y clima extremo. Caracter\u00edsticas como rodamientos de complemento completo, carcasas reforzadas y sistemas de sellado avanzados garantizan que la caja de engranajes soporte cargas pesadas continuas. Su durabilidad minimiza las aver\u00edas, reduce las necesidades de mantenimiento y mejora la fiabilidad en entornos industriales o de construcci\u00f3n exigentes.<\/p>\n<p><strong>4. Evaluar los \u00edndices de eficiencia<\/strong><br \/>\nElija una caja de engranajes planetarios con una eficiencia mec\u00e1nica superior a 95%, que optimiza el consumo de energ\u00eda y minimiza la generaci\u00f3n de calor durante operaciones continuas. Su alta eficiencia reduce el consumo de combustible, garantiza un rendimiento sostenido en ciclos de trabajo intensivos y asegura la estabilidad t\u00e9rmica. Esto es especialmente importante para gr\u00faas sobre orugas que operan en aplicaciones que requieren tareas prolongadas de elevaci\u00f3n o movimiento con cargas pesadas.<\/p>\n<p><strong>5. Verifique la compatibilidad con el sistema de gr\u00faa.<\/strong><br \/>\nAseg\u00farese de que el motorreductor planetario seleccionado se integre perfectamente con el tren de rodaje, el tama\u00f1o de las orugas, las ruedas dentadas y el tipo de motor de la gr\u00faa. Verifique las dimensiones de montaje y los est\u00e1ndares de interfaz para evitar modificaciones costosas. Una compatibilidad adecuada simplifica la instalaci\u00f3n, mantiene la estabilidad operativa y garantiza una propulsi\u00f3n fluida, proporcionando un rendimiento fiable en diversos terrenos y escenarios de elevaci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4649 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Crawler-Cranes-1.webp\" alt=\"Transmisi\u00f3n planetaria para gr\u00faas sobre orugas\" width=\"800\" height=\"800\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Crawler-Cranes-1.webp 800w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/08\/Planetary-Track-Drive-for-Crawler-Cranes-1-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>La caja de engranajes planetarios para orugas es un sistema de transmisi\u00f3n especializado, esencial para las gr\u00faas sobre orugas. Est\u00e1 dise\u00f1ada para proporcionar una propulsi\u00f3n de alto par a los trenes de rodaje en entornos exigentes de construcci\u00f3n y elevaci\u00f3n de cargas pesadas. Funciona como un conjunto compacto de engranajes epic\u00edclicos que convierte la potencia de entrada de un motor hidr\u00e1ulico o el\u00e9ctrico en un par de salida amplificado, lo que permite a la gr\u00faa desplazarse por terrenos irregulares o blandos con estabilidad y eficiencia. Sus componentes clave incluyen un engranaje solar central, varios engranajes planetarios montados sobre un soporte, una corona dentada exterior y una carcasa robusta llena de aceite lubricante para minimizar la fricci\u00f3n y el desgaste.<\/p>","protected":false},"featured_media":4505,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[195,194],"product_tag":[200,203,201,202,199,198,196,197],"class_list":{"0":"post-4646","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-planetary-track-drive","7":"product_cat-planetary-gearboxes","8":"product_tag-planetary-gear-reducers","9":"product_tag-planetary-gearbox-for-sale","10":"product_tag-planetary-gearbox-manufacturers","11":"product_tag-planetary-gearbox-suppliers","12":"product_tag-planetary-gearboxes","13":"product_tag-planetary-track-drive","14":"product_tag-planetary-track-drive-gearbox","15":"product_tag-track-drive-planetary-gearbox","17":"first","18":"instock","19":"shipping-taxable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/product\/4646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/comments?post=4646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/media\/4505"}],"wp:attachment":[{"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/media?parent=4646"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/product_brand?post=4646"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/product_cat?post=4646"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/korea-transmission.com\/es\/wp-json\/wp\/v2\/product_tag?post=4646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}