{"id":5235,"date":"2025-09-06T01:57:08","date_gmt":"2025-09-06T01:57:08","guid":{"rendered":"https:\/\/korea-transmission.com\/?post_type=product&#038;p=5235"},"modified":"2025-09-06T03:46:32","modified_gmt":"2025-09-06T03:46:32","slug":"planetary-winch-drive-gearbox-for-pipelayers","status":"publish","type":"product","link":"https:\/\/korea-transmission.com\/de\/produkt\/planetary-winch-drive-gearbox-for-pipelayers\/","title":{"rendered":"Planetengetriebe f\u00fcr Windenantriebe f\u00fcr Rohrleger"},"content":{"rendered":"<p>Ein Planetengetriebe f\u00fcr Rohrverlegemaschinen ist eine spezielle mechanische Komponente zur Leistungssteigerung von Windensystemen in Rohrverlegemaschinen. Es wird zur Verlegung von Rohrleitungen mit gro\u00dfem Durchmesser im Bauwesen und in der \u00d6l- und Gasindustrie eingesetzt. Das Planetengetriebe besteht aus einem zentralen Sonnenrad, mehreren darum kreisenden Planetenr\u00e4dern und einem \u00e4u\u00dferen Hohlrad. Alle Komponenten sind in einem kompakten, rotierenden Geh\u00e4use untergebracht. Direkt in die Windentrommel integriert, erm\u00f6glicht es die effiziente \u00dcbertragung hoher Drehmomente und Drehzahlreduzierungen und somit die pr\u00e4zise Steuerung des Hebens, Senkens und Positionierens schwerer Rohre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5120 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Pipelayers.webp\" alt=\"Planetenwindenantrieb f\u00fcr Rohrverleger\" width=\"800\" height=\"800\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Pipelayers.webp 800w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Pipelayers-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<h2>Abmessungen des Planetenwindenantriebs<\/h2>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5191 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-1.webp\" alt=\"Abmessungen des Planetenwindenantriebs\" width=\"1246\" height=\"651\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-1.webp 1246w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-1-980x512.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-1-480x251.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1246px, 100vw\" \/> Allgemeine Abmessungen<\/h3>\n<table style=\"height: 340px; width: 100%;\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">Typ<\/td>\n<td style=\"text-align: center;\" width=\"52\">A<\/td>\n<td style=\"text-align: center;\" width=\"62\">B<\/td>\n<td style=\"text-align: center;\" width=\"62\">E<\/td>\n<td style=\"text-align: center;\" width=\"62\">F<\/td>\n<td style=\"text-align: center;\" width=\"62\">G<\/td>\n<td style=\"text-align: center;\" width=\"62\">H<\/td>\n<td style=\"text-align: center;\" width=\"62\">L<\/td>\n<td style=\"text-align: center;\" width=\"62\">M<\/td>\n<td style=\"text-align: center;\" width=\"52\">N<\/td>\n<td style=\"text-align: center;\" width=\"52\">P<\/td>\n<td style=\"text-align: center;\" width=\"84\">Q<\/td>\n<td style=\"text-align: center;\" width=\"52\">1. Quartal<\/td>\n<td style=\"text-align: center;\" width=\"94\">R<\/td>\n<td style=\"text-align: center;\" width=\"52\">Y<\/td>\n<td style=\"text-align: center;\" width=\"62\">Z<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">WD 1023<\/td>\n<td style=\"text-align: center;\">290<\/td>\n<td style=\"text-align: center;\" width=\"62\">200 f7<\/td>\n<td style=\"text-align: center;\" width=\"62\">295 f7<\/td>\n<td style=\"text-align: center;\">320<\/td>\n<td style=\"text-align: center;\">348<\/td>\n<td style=\"text-align: center;\">99<\/td>\n<td style=\"text-align: center;\">383<\/td>\n<td style=\"text-align: center;\">40<\/td>\n<td style=\"text-align: center;\">5<\/td>\n<td style=\"text-align: center;\">41<\/td>\n<td style=\"text-align: center;\" width=\"84\">M16 (16)<\/td>\n<td style=\"text-align: center;\">24<\/td>\n<td style=\"text-align: center;\" width=\"94\">\u00d817 (18)<\/td>\n<td style=\"text-align: center;\">255<\/td>\n<td style=\"text-align: center;\">20<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">WD 1523<\/td>\n<td style=\"text-align: center;\">328<\/td>\n<td style=\"text-align: center;\" width=\"62\">230 f7<\/td>\n<td style=\"text-align: center;\" width=\"62\">335 f7<\/td>\n<td style=\"text-align: center;\">368<\/td>\n<td style=\"text-align: center;\">398<\/td>\n<td style=\"text-align: center;\">68<\/td>\n<td style=\"text-align: center;\">414<\/td>\n<td style=\"text-align: center;\">37<\/td>\n<td style=\"text-align: center;\">5<\/td>\n<td style=\"text-align: center;\">34<\/td>\n<td style=\"text-align: center;\" width=\"84\">M16 (22)<\/td>\n<td style=\"text-align: center;\">24<\/td>\n<td style=\"text-align: center;\" width=\"94\">\u00d817 (24)<\/td>\n<td style=\"text-align: center;\">280<\/td>\n<td style=\"text-align: center;\">23<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">WD 2003<\/td>\n<td style=\"text-align: center;\">355<\/td>\n<td style=\"text-align: center;\" width=\"62\">270 f7<\/td>\n<td style=\"text-align: center;\" width=\"62\">366 f7<\/td>\n<td style=\"text-align: center;\">394<\/td>\n<td style=\"text-align: center;\">424<\/td>\n<td style=\"text-align: center;\" width=\"62\">57,5<\/td>\n<td style=\"text-align: center;\">424.5<\/td>\n<td style=\"text-align: center;\">37<\/td>\n<td style=\"text-align: center;\">5<\/td>\n<td style=\"text-align: center;\">45<\/td>\n<td style=\"text-align: center;\" width=\"84\">M16 (22)<\/td>\n<td style=\"text-align: center;\">24<\/td>\n<td style=\"text-align: center;\" width=\"94\">\u00d817 (24)<\/td>\n<td style=\"text-align: center;\">320<\/td>\n<td style=\"text-align: center;\">23<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">WD 2523<\/td>\n<td style=\"text-align: center;\">394<\/td>\n<td style=\"text-align: center;\" width=\"62\">300 f7<\/td>\n<td style=\"text-align: center;\" width=\"62\">402 f7<\/td>\n<td style=\"text-align: center;\">424<\/td>\n<td style=\"text-align: center;\">450<\/td>\n<td style=\"text-align: center;\">81<\/td>\n<td style=\"text-align: center;\">462<\/td>\n<td style=\"text-align: center;\">50<\/td>\n<td style=\"text-align: center;\">5<\/td>\n<td style=\"text-align: center;\">53<\/td>\n<td style=\"text-align: center;\" width=\"84\">M20 (22)<\/td>\n<td style=\"text-align: center;\">30<\/td>\n<td style=\"text-align: center;\" width=\"94\">\u00d814,5 (36)<\/td>\n<td style=\"text-align: center;\">350<\/td>\n<td style=\"text-align: center;\">25<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">WD 3003<\/td>\n<td style=\"text-align: center;\">432<\/td>\n<td style=\"text-align: center;\" width=\"62\">330 f7<\/td>\n<td style=\"text-align: center;\" width=\"62\">436 f7<\/td>\n<td style=\"text-align: center;\">465<\/td>\n<td style=\"text-align: center;\">495<\/td>\n<td style=\"text-align: center;\" width=\"62\">87,5<\/td>\n<td style=\"text-align: center;\">477<\/td>\n<td style=\"text-align: center;\">50<\/td>\n<td style=\"text-align: center;\">5<\/td>\n<td style=\"text-align: center;\">60<\/td>\n<td style=\"text-align: center;\" width=\"84\">M20 (22)<\/td>\n<td style=\"text-align: center;\">30<\/td>\n<td style=\"text-align: center;\" width=\"94\">\u00d819 (30)<\/td>\n<td style=\"text-align: center;\">390<\/td>\n<td style=\"text-align: center;\">25<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">WD 4803<\/td>\n<td style=\"text-align: center;\">470<\/td>\n<td style=\"text-align: center;\" width=\"62\">355 f7<\/td>\n<td style=\"text-align: center;\" width=\"62\">476 f7<\/td>\n<td style=\"text-align: center;\">508<\/td>\n<td style=\"text-align: center;\">545<\/td>\n<td style=\"text-align: center;\">128<\/td>\n<td style=\"text-align: center;\">575<\/td>\n<td style=\"text-align: center;\">60<\/td>\n<td style=\"text-align: center;\">5<\/td>\n<td style=\"text-align: center;\">38<\/td>\n<td style=\"text-align: center;\" width=\"84\">M24 (22)<\/td>\n<td style=\"text-align: center;\">34<\/td>\n<td style=\"text-align: center;\" width=\"94\">\u00d824 (24)<\/td>\n<td style=\"text-align: center;\">420<\/td>\n<td style=\"text-align: center;\">30<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">WD 8003<\/td>\n<td style=\"text-align: center;\">530<\/td>\n<td style=\"text-align: center;\" width=\"62\">430 f7<\/td>\n<td style=\"text-align: center;\" width=\"62\">544 f7<\/td>\n<td style=\"text-align: center;\">578<\/td>\n<td style=\"text-align: center;\">618<\/td>\n<td style=\"text-align: center;\" width=\"62\">129,5<\/td>\n<td style=\"text-align: center;\">688<\/td>\n<td style=\"text-align: center;\">55<\/td>\n<td style=\"text-align: center;\">5<\/td>\n<td style=\"text-align: center;\">45<\/td>\n<td style=\"text-align: center;\" width=\"84\">M24 (22)<\/td>\n<td style=\"text-align: center;\">36<\/td>\n<td style=\"text-align: center;\" width=\"94\">\u00d824 (30)<\/td>\n<td style=\"text-align: center;\">480<\/td>\n<td style=\"text-align: center;\">35<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"136\">WD 16004*<\/td>\n<td style=\"text-align: center;\">615<\/td>\n<td style=\"text-align: center;\" width=\"62\">515 h7<\/td>\n<td style=\"text-align: center;\" width=\"62\">640 h7<\/td>\n<td style=\"text-align: center;\">690<\/td>\n<td style=\"text-align: center;\">750<\/td>\n<td style=\"text-align: center;\">129<\/td>\n<td style=\"text-align: center;\">966<\/td>\n<td style=\"text-align: center;\">110<\/td>\n<td style=\"text-align: center;\">5<\/td>\n<td style=\"text-align: center;\">9<\/td>\n<td style=\"text-align: center;\" width=\"84\">M30 (24)<\/td>\n<td style=\"text-align: center;\">52<\/td>\n<td style=\"text-align: center;\" width=\"94\">\u00d833 (24)<\/td>\n<td style=\"text-align: center;\">565<\/td>\n<td style=\"text-align: center;\">30<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>* Motoradapter auf Anfrage<\/p>\n<h3>Eingabedimensionen<\/h3>\n<table style=\"height: 200px; border-collapse: collapse; width: 100%;\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 15.00pt;\">\n<td class=\"et2\" style=\"height: 15pt; width: 75.6pt; text-align: center;\" width=\"126\" height=\"25\"><\/td>\n<td class=\"et3\" style=\"width: 50.4pt; text-align: center;\" width=\"84\"><span class=\"font4\">C<\/span><\/td>\n<td class=\"et3\" style=\"width: 68.4pt; text-align: center;\" width=\"114\"><span class=\"font4\">D<\/span><\/td>\n<td class=\"et4\" style=\"width: 50.4pt; text-align: center;\" width=\"84\"><span class=\"font4\">H1<\/span><\/td>\n<td class=\"et5\" style=\"width: 56.4pt; text-align: center;\" width=\"94\"><span class=\"font4\">T<\/span><\/td>\n<td class=\"et5\" style=\"width: 56.4pt; text-align: center;\" width=\"94\"><span class=\"font4\">U<\/span><\/td>\n<td class=\"et3\" style=\"width: 56.4pt; text-align: center;\" width=\"94\"><span class=\"font4\">V<\/span><\/td>\n<td class=\"et3\" style=\"width: 50.4pt; text-align: center;\" width=\"84\"><span class=\"font4\">W<\/span><\/td>\n<td class=\"et3\" style=\"width: 68.4pt; text-align: center;\" width=\"114\"><span class=\"font4\">S1<\/span><\/td>\n<td class=\"et3\" style=\"width: 43.2pt; text-align: center;\" width=\"72\"><span class=\"font4\">J<\/span><\/td>\n<td class=\"et3\" style=\"width: 62.4pt; text-align: center;\" width=\"104\"><span class=\"font4\">S2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et6\" style=\"height: 13.5pt; width: 75.6pt; text-align: center;\" width=\"126\" height=\"22\"><span class=\"font4\">Eingang SAE B<\/span><\/td>\n<td class=\"et7\" style=\"width: 50.4pt; text-align: center;\" width=\"84\"><span class=\"font5\">101.6 H8<\/span><\/td>\n<td class=\"et8\" style=\"width: 68.4pt; text-align: center;\" width=\"114\"><span class=\"font5\">DP16\/32 Z13<\/span><\/td>\n<td class=\"et9\" style=\"text-align: center;\">20<\/td>\n<td class=\"et10\" style=\"text-align: center;\">10<\/td>\n<td class=\"et10\" style=\"text-align: center;\">7<\/td>\n<td class=\"et11\" style=\"text-align: center;\">37<\/td>\n<td class=\"et11\" style=\"text-align: center;\">127<\/td>\n<td class=\"et8\" style=\"width: 68.4pt; text-align: center;\" width=\"114\"><span class=\"font5\">Nr. 4 M12<\/span><\/td>\n<td class=\"et11\" style=\"text-align: center;\">146<\/td>\n<td class=\"et8\" style=\"width: 62.4pt; text-align: center;\" width=\"104\"><span class=\"font5\">Nr. 2 M14<\/span><\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et6\" style=\"height: 13.5pt; width: 75.6pt; text-align: center;\" width=\"126\" height=\"22\"><span class=\"font4\">Eingang SAE C<\/span><\/td>\n<td class=\"et12\" style=\"width: 50.4pt; text-align: center;\" width=\"84\"><span class=\"font5\">127 F8<\/span><\/td>\n<td class=\"et8\" style=\"width: 68.4pt; text-align: center;\" width=\"114\"><span class=\"font5\">DP12\/24 Z14<\/span><\/td>\n<td class=\"et9\" style=\"text-align: center;\">30<\/td>\n<td class=\"et10\" style=\"text-align: center;\">15<\/td>\n<td class=\"et10\" style=\"text-align: center;\">16<\/td>\n<td class=\"et11\" style=\"text-align: center;\">56<\/td>\n<td class=\"et11\" style=\"text-align: center;\">162<\/td>\n<td class=\"et8\" style=\"width: 68.4pt; text-align: center;\" width=\"114\"><span class=\"font5\">Nr. 4 M12<\/span><\/td>\n<td class=\"et11\" style=\"text-align: center;\">181<\/td>\n<td class=\"et8\" style=\"width: 62.4pt; text-align: center;\" width=\"104\"><span class=\"font5\">Nr. 2 M16<\/span><\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et6\" style=\"height: 13.5pt; width: 75.6pt; text-align: center;\" width=\"126\" height=\"22\"><span class=\"font4\">Eingang SAE D<\/span><\/td>\n<td class=\"et7\" style=\"width: 50.4pt; text-align: center;\" width=\"84\"><span class=\"font5\">152.4 F8<\/span><\/td>\n<td class=\"et8\" style=\"width: 68.4pt; text-align: center;\" width=\"114\"><span class=\"font5\">DP8\/16 Z13<\/span><\/td>\n<td class=\"et9\" style=\"text-align: center;\">40<\/td>\n<td class=\"et10\" style=\"text-align: center;\">15<\/td>\n<td class=\"et10\" style=\"text-align: center;\">28<\/td>\n<td class=\"et11\" style=\"text-align: center;\">75<\/td>\n<td class=\"et11\" style=\"text-align: center;\">229<\/td>\n<td class=\"et8\" style=\"width: 68.4pt; text-align: center;\" width=\"114\"><span class=\"font5\">Nr. 4 M20<\/span><\/td>\n<td class=\"et8\" style=\"width: 43.2pt; text-align: center;\" width=\"72\"><span class=\"font5\">\/<\/span><\/td>\n<td class=\"et8\" style=\"width: 62.4pt; text-align: center;\" width=\"104\"><span class=\"font5\">\/<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5192 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-2.webp\" alt=\"Abmessungen des Planetenwindenantriebs\" width=\"1320\" height=\"730\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-2.webp 1320w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-2-1280x708.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-2-980x542.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-2-480x265.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1320px, 100vw\" \/><\/p>\n<h3>WDD \u2013 Allgemeine Abmessungen<\/h3>\n<table style=\"width: 100%;\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 8.99358%; text-align: center;\" width=\"126\">Typ<\/td>\n<td style=\"width: 3.85439%; text-align: center;\" width=\"52\">A<\/td>\n<td style=\"width: 3.74733%; text-align: center;\" width=\"52\">B<\/td>\n<td style=\"width: 4.17559%; text-align: center;\" width=\"30\">C<\/td>\n<td style=\"width: 4.06853%; text-align: center;\" width=\"42\">D<\/td>\n<td style=\"width: 4.92505%; text-align: center;\" width=\"42\">E<\/td>\n<td style=\"width: 4.60382%; text-align: center;\" width=\"42\">F<\/td>\n<td style=\"width: 3.64022%; text-align: center;\" width=\"42\">G<\/td>\n<td style=\"width: 4.60385%; text-align: center;\" width=\"42\">H<\/td>\n<td style=\"width: 5.13922%; text-align: center;\" width=\"42\">ICH<\/td>\n<td style=\"width: 4.28265%; text-align: center;\" width=\"42\">L<\/td>\n<td style=\"width: 4.60385%; text-align: center;\" width=\"42\">M<\/td>\n<td style=\"width: 3.85439%; text-align: center;\" width=\"42\">N<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 8.99358%; text-align: center;\" width=\"126\">WDD A75<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">285<\/td>\n<td style=\"width: 3.74733%; text-align: center;\">74<\/td>\n<td style=\"width: 4.17559%; text-align: center;\">15<\/td>\n<td style=\"width: 4.06853%; text-align: center;\">10.5<\/td>\n<td style=\"width: 4.92505%; text-align: center;\">85<\/td>\n<td style=\"width: 4.60382%; text-align: center;\">99<\/td>\n<td style=\"width: 3.64022%; text-align: center;\">451<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">175<\/td>\n<td style=\"width: 5.13922%; text-align: center;\">200<\/td>\n<td style=\"width: 4.28265%; text-align: center;\">225<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">341<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">255<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 8.99358%; text-align: center;\" width=\"126\">WDD B100<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">315<\/td>\n<td style=\"width: 3.74733%; text-align: center;\">79<\/td>\n<td style=\"width: 4.17559%; text-align: center;\">20<\/td>\n<td style=\"width: 4.06853%; text-align: center;\">12.5<\/td>\n<td style=\"width: 4.92505%; text-align: center;\">93<\/td>\n<td style=\"width: 4.60382%; text-align: center;\">68<\/td>\n<td style=\"width: 3.64022%; text-align: center;\">494<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">200<\/td>\n<td style=\"width: 5.13922%; text-align: center;\">230<\/td>\n<td style=\"width: 4.28265%; text-align: center;\">260<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">392<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">280<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 8.99358%; text-align: center;\" width=\"126\">WDD C130<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">355<\/td>\n<td style=\"width: 3.74733%; text-align: center;\">79<\/td>\n<td style=\"width: 4.17559%; text-align: center;\">20<\/td>\n<td style=\"width: 4.06853%; text-align: center;\">13<\/td>\n<td style=\"width: 4.92505%; text-align: center;\">93<\/td>\n<td style=\"width: 4.60382%; text-align: center;\">58<\/td>\n<td style=\"width: 3.64022%; text-align: center;\">514<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">200<\/td>\n<td style=\"width: 5.13922%; text-align: center;\">230<\/td>\n<td style=\"width: 4.28265%; text-align: center;\">260<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">416<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">320<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 8.99358%; text-align: center;\" width=\"126\">WDD D155<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">385<\/td>\n<td style=\"width: 3.74733%; text-align: center;\">94<\/td>\n<td style=\"width: 4.17559%; text-align: center;\">20<\/td>\n<td style=\"width: 4.06853%; text-align: center;\">17<\/td>\n<td style=\"width: 4.92505%; text-align: center;\">110<\/td>\n<td style=\"width: 4.60382%; text-align: center;\">81<\/td>\n<td style=\"width: 3.64022%; text-align: center;\">554<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">230<\/td>\n<td style=\"width: 5.13922%; text-align: center;\">260<\/td>\n<td style=\"width: 4.28265%; text-align: center;\">290<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">443<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">350<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 8.99358%; text-align: center;\" width=\"126\">WDD E190<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">425<\/td>\n<td style=\"width: 3.74733%; text-align: center;\">99<\/td>\n<td style=\"width: 4.17559%; text-align: center;\">25<\/td>\n<td style=\"width: 4.06853%; text-align: center;\">21<\/td>\n<td style=\"width: 4.92505%; text-align: center;\">135<\/td>\n<td style=\"width: 4.60382%; text-align: center;\">87.5<\/td>\n<td style=\"width: 3.64022%; text-align: center;\">592.5<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">260<\/td>\n<td style=\"width: 5.13922%; text-align: center;\">310<\/td>\n<td style=\"width: 4.28265%; text-align: center;\">360<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">490<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">390<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 8.99358%; text-align: center;\" width=\"126\">WDD F230<\/td>\n<td style=\"width: 3.85439%; text-align: center;\" width=\"104\">460<\/td>\n<td style=\"width: 3.74733%; text-align: center;\">118.5<\/td>\n<td style=\"width: 4.17559%; text-align: center;\">30<\/td>\n<td style=\"width: 4.06853%; text-align: center;\">21<\/td>\n<td style=\"width: 4.92505%; text-align: center;\">139.5<\/td>\n<td style=\"width: 4.60382%; text-align: center;\" width=\"126\">60<\/td>\n<td style=\"width: 3.64022%; text-align: center;\">678<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">260<\/td>\n<td style=\"width: 5.13922%; text-align: center;\">310<\/td>\n<td style=\"width: 4.28265%; text-align: center;\">360<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">540<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">420<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 8.99358%; text-align: center;\" width=\"126\">WDD G300<\/td>\n<td style=\"width: 3.85439%; text-align: center;\" width=\"104\">530<\/td>\n<td style=\"width: 3.74733%; text-align: center;\">118.5<\/td>\n<td style=\"width: 4.17559%; text-align: center;\">30<\/td>\n<td style=\"width: 4.06853%; text-align: center;\" width=\"210\">21<\/td>\n<td style=\"width: 4.92505%; text-align: center;\">147<\/td>\n<td style=\"width: 4.60382%; text-align: center;\">61<\/td>\n<td style=\"width: 3.64022%; text-align: center;\">780.5<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">300<\/td>\n<td style=\"width: 5.13922%; text-align: center;\">350<\/td>\n<td style=\"width: 4.28265%; text-align: center;\">400<\/td>\n<td style=\"width: 4.60385%; text-align: center;\">610<\/td>\n<td style=\"width: 3.85439%; text-align: center;\">480<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 4.71091%; text-align: center;\" width=\"42\">P<\/td>\n<td style=\"width: 4.81799%; text-align: center;\" width=\"42\">Q<\/td>\n<td style=\"width: 9.31477%; text-align: center;\" width=\"84\">R<\/td>\n<td style=\"width: 2.67666%; text-align: center;\" width=\"30\">S<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">T<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">U<\/td>\n<td style=\"width: 9.31478%; text-align: center;\" colspan=\"3\" width=\"126\">V Lmin Y<\/td>\n<td style=\"width: 1.71306%; text-align: center;\" width=\"20\">Z<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 4.71091%; text-align: center;\">200<\/td>\n<td style=\"width: 4.81799%; text-align: center;\">359<\/td>\n<td style=\"width: 9.31477%; text-align: center;\" width=\"84\">Nr. 16-M16<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">32<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">20\u00b0<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">20\u00b0<\/td>\n<td style=\"width: 3.96146%; text-align: center;\">117<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">320<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">560<\/td>\n<td style=\"width: 1.71306%; text-align: center;\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 4.71091%; text-align: center;\">230<\/td>\n<td style=\"width: 4.81799%; text-align: center;\">412<\/td>\n<td style=\"width: 9.31477%; text-align: center;\" width=\"84\">Nr. 22-M16<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">32<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.96146%; text-align: center;\">132<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">350<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">630<\/td>\n<td style=\"width: 1.71306%; text-align: center;\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 4.71091%; text-align: center;\">270<\/td>\n<td style=\"width: 4.81799%; text-align: center;\">438<\/td>\n<td style=\"width: 9.31477%; text-align: center;\" width=\"84\">Nr. 22-M16<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">32<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.96146%; text-align: center;\">152<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">370<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">690<\/td>\n<td style=\"width: 1.71306%; text-align: center;\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 4.71091%; text-align: center;\">300<\/td>\n<td style=\"width: 4.81799%; text-align: center;\">467<\/td>\n<td style=\"width: 9.31477%; text-align: center;\" width=\"84\">Nr. 22-M20<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">35<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.96146%; text-align: center;\">168<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">385<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">720<\/td>\n<td style=\"width: 1.71306%; text-align: center;\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 4.71091%; text-align: center;\">330<\/td>\n<td style=\"width: 4.81799%; text-align: center;\">516<\/td>\n<td style=\"width: 9.31477%; text-align: center;\" width=\"84\">Nr. 22-M20<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">35<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.96146%; text-align: center;\">184<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">390<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">790<\/td>\n<td style=\"width: 1.71306%; text-align: center;\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 4.71091%; text-align: center;\">355<\/td>\n<td style=\"width: 4.81799%; text-align: center;\">568<\/td>\n<td style=\"width: 9.31477%; text-align: center;\" width=\"84\">Nr. 22-M24<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">35<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.96146%; text-align: center;\">195.5<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">465<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">865<\/td>\n<td style=\"width: 1.71306%; text-align: center;\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 4.71091%; text-align: center;\">430<\/td>\n<td style=\"width: 4.81799%; text-align: center;\">640<\/td>\n<td style=\"width: 9.31477%; text-align: center;\" width=\"84\">Nr. 22-M24<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">35<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.64026%; text-align: center;\" width=\"42\">15\u00b0<\/td>\n<td style=\"width: 3.96146%; text-align: center;\" width=\"84\">233<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">560<\/td>\n<td style=\"width: 2.67666%; text-align: center;\">980<\/td>\n<td style=\"width: 1.71306%; text-align: center;\">5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>WDD-Auftritte<\/h3>\n<table style=\"border-collapse: collapse; width: 100%;\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.5pt; width: 138pt; text-align: center;\" width=\"230\" height=\"22\"><\/td>\n<td class=\"et3\" style=\"width: 232.8pt; text-align: center;\" width=\"388\"><span class=\"font3\">[Dan]<\/span><\/td>\n<td class=\"et4\" style=\"width: 276pt; text-align: center;\" colspan=\"2\" width=\"460\"><span class=\"font3\">[mm]<\/span><\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et5\" style=\"height: 13.5pt; width: 138pt; text-align: center;\" width=\"230\" height=\"22\"><span class=\"font3\">WDD A75<\/span><\/td>\n<td class=\"et6\" style=\"text-align: center;\">7500<\/td>\n<td class=\"et7\" style=\"text-align: center;\" colspan=\"2\">18<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et5\" style=\"height: 13.5pt; width: 138pt; text-align: center;\" width=\"230\" height=\"22\"><span class=\"font3\">WDD B100<\/span><\/td>\n<td class=\"et6\" style=\"text-align: center;\">10000<\/td>\n<td class=\"et7\" style=\"text-align: center;\" colspan=\"2\">20<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et5\" style=\"height: 13.5pt; width: 138pt; text-align: center;\" width=\"230\" height=\"22\"><span class=\"font3\">WDD C130<\/span><\/td>\n<td class=\"et6\" style=\"text-align: center;\">13000<\/td>\n<td class=\"et7\" style=\"text-align: center;\" colspan=\"2\">22<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et5\" style=\"height: 13.5pt; width: 138pt; text-align: center;\" width=\"230\" height=\"22\"><span class=\"font3\">WDD D155<\/span><\/td>\n<td class=\"et6\" style=\"text-align: center;\">15500<\/td>\n<td class=\"et7\" style=\"text-align: center;\" colspan=\"2\">24<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et5\" style=\"height: 13.5pt; width: 138pt; text-align: center;\" width=\"230\" height=\"22\"><span class=\"font3\">WDD E190<\/span><\/td>\n<td class=\"et6\" style=\"text-align: center;\">19000<\/td>\n<td class=\"et7\" style=\"text-align: center;\" colspan=\"2\">26<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et5\" style=\"height: 13.5pt; width: 138pt; text-align: center;\" width=\"230\" height=\"22\"><span class=\"font3\">WDD F230<\/span><\/td>\n<td class=\"et6\" style=\"text-align: center;\">23000<\/td>\n<td class=\"et7\" style=\"text-align: center;\" colspan=\"2\">28<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et5\" style=\"height: 13.5pt; width: 138pt; text-align: center;\" width=\"230\" height=\"22\"><span class=\"font3\">WDD G300<\/span><\/td>\n<td class=\"et6\" style=\"text-align: center;\">30000<\/td>\n<td class=\"et7\" style=\"text-align: center;\" colspan=\"2\">32<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>WD-Auftritte<\/h3>\n<table style=\"height: 2210px; width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 47px;\">\n<td style=\"width: 16.2928%; height: 47px; text-align: center;\" width=\"378\">Gr\u00f6\u00dfe<\/td>\n<td style=\"width: 14.2558%; height: 47px; text-align: center;\">\u00a0\u00a0ich<br \/>\ne<\/td>\n<td style=\"width: 15.0831%; height: 47px; text-align: center;\" width=\"186\">T2 weiblich<br \/>\n[Nm]<\/td>\n<td style=\"width: 13.9233%; height: 47px; text-align: center;\" width=\"166\">Td-max<br \/>\n[Nm]<\/td>\n<td style=\"width: 19.7536%; height: 47px; text-align: center;\" width=\"166\">Ts-max<br \/>\n[Nm]<\/td>\n<td style=\"width: 27.0296%; height: 47px; text-align: center;\" width=\"186\">n1-max [U\/min]<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 16.2928%; height: 253px; text-align: center;\" rowspan=\"11\">WD 1023<\/td>\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">52.83<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">62.55<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">74.03<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">78.70<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">93.09<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">108.45<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">111.15<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">117.00<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">131.40<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">136.27<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 14.2558%; height: 23px; text-align: center;\">165.05<\/td>\n<td style=\"width: 15.0831%; height: 23px; text-align: center;\">18100<\/td>\n<td style=\"width: 13.9233%; height: 23px; text-align: center;\">26900<\/td>\n<td style=\"width: 19.7536%; height: 23px; text-align: center;\">33400<\/td>\n<td style=\"width: 27.0296%; height: 23px; text-align: center;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 16.2928%; text-align: center; height: 300px;\" rowspan=\"13\"><span class=\"font3\">WD 1523<\/span><\/td>\n<td class=\"et3\" style=\"width: 14.2558%; text-align: center; height: 23px;\" width=\"168\">51.46<\/td>\n<td class=\"et4\" style=\"width: 15.0831%; text-align: center; height: 23px;\" width=\"176\">26100<\/td>\n<td class=\"et5\" style=\"width: 13.9233%; text-align: center; height: 23px;\" width=\"166\">43200<\/td>\n<td class=\"et6\" style=\"width: 19.7536%; text-align: center; height: 23px;\" width=\"166\">60000<\/td>\n<td class=\"et5\" style=\"width: 27.0296%; text-align: center; height: 23px;\" width=\"166\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">60.16<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26200<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">71.21<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26300<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">74.11<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26300<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 24px;\">76.71<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 24px;\">26300<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 24px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 24px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 24px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">87.67<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26300<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">89.61<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26350<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">104.33<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26350<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">108.29<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">24900<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">110.27<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26400<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">126.42<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26400<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et7\" style=\"width: 14.2558%; text-align: center; height: 23px;\">128.35<\/td>\n<td class=\"et8\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26400<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et10\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et9\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td class=\"et12\" style=\"width: 14.2558%; text-align: center; height: 23px;\">155.48<\/td>\n<td class=\"et13\" style=\"text-align: center; width: 15.0831%; height: 23px;\">26500<\/td>\n<td class=\"et14\" style=\"text-align: center; width: 13.9233%; height: 23px;\">43200<\/td>\n<td class=\"et15\" style=\"text-align: center; width: 19.7536%; height: 23px;\">60000<\/td>\n<td class=\"et14\" style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 16.2928%; text-align: center; height: 276px;\" rowspan=\"12\"><span class=\"font3\">WD 2003<\/span><\/td>\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"388\">48.16<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\" width=\"168\">33800<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\" width=\"168\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\" width=\"178\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\" width=\"168\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">56.31<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">57.03<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">34000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">66.66<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33800<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">69.38<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"388\">\u00a071.82<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">34100<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">82.09<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">83.90<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33650<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">97.70<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33650<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">103.26<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">120.21<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">145.62<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">33000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">57900<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">80000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 16.2928%; height: 345px; text-align: center;\" rowspan=\"15\">WD 2523<\/td>\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">50.29<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44050<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">58.82<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44200<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">59.55<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44200<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">69.62<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44300<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">72.44<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44300<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">75.0<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44350<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">85.70<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44350<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"388\">\u00a087.34<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44450<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">97.99<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">42450<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">102.02<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">105.86<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">107.79<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">123.62<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">125.48<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44600<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">152.00<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">44600<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">72800<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">105000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 16.2928%; height: 276px; text-align: center;\" rowspan=\"12\">WD 3003<\/td>\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"388\">49.75<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\" width=\"168\">48200<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\" width=\"168\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\" width=\"178\">136500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\" width=\"168\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">58.19<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">48250<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">136500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">68.02<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">47620<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">133700<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">71.66<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">48200<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">136500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">81.97<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">48200<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">136500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"388\">\u00a083.74<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">48250<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">133700<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">95.75<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">47900<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">133700<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">96.70<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">48400<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">136500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">103.04<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">46800<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">90600<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">121200<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">112.94<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">47600<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">94700<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">133700<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">117.79<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">46800<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">90600<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">121200<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">138.88<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">46800<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">90600<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">121200<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 16.2928%; text-align: center; height: 230px;\" rowspan=\"10\">WD 4803<\/td>\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">51.99<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">69850<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">160000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">61.55<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">69350<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">160000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">71.58<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">83750<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">168500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">77.49<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">67500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">160000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">84.68<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">84000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">168500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"388\">90.26<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">66650<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">160000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">106.51<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">84100<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">168500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">109.39<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">52000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">103200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">160000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">123.99<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">84000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">168500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">150.20<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">70000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">123300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">168500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 16.2928%; text-align: center; height: 253px;\" rowspan=\"11\">WD 8003<\/td>\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">56.0<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\" width=\"178\">125250<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\" width=\"168\">197200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\" width=\"178\">312000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\" width=\"168\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">65.45<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">125400<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">197200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">312000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">73.1<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">122000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">197200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">312000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">85.4<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">122700<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">197200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">312000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">92.17<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">125500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">197200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">298100<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">105.08<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">123000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">197200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">312000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">108.71<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">125000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">184300<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">304500<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">120.12<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">122900<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">197200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">312000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">126.50<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">96500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">174500<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">221600<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">141.63<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">122300<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">197200<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">312000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">170.43<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">96800<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">174500<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">221600<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 16.2928%; height: 230px; text-align: center;\" rowspan=\"10\">WD 16004<\/td>\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">200<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">227000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">233,38<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">223800<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">274,31<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">233300<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\">320<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">232500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">\u00a0370,13<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">219000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">393,12<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">233300<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">431,73<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">219000<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">528,91<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">233500<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">605,67<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">219200<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"text-align: center; width: 14.2558%; height: 23px;\" width=\"378\">713,35<\/td>\n<td style=\"text-align: center; width: 15.0831%; height: 23px;\">219200<\/td>\n<td style=\"text-align: center; width: 13.9233%; height: 23px;\">317000<\/td>\n<td style=\"text-align: center; width: 19.7536%; height: 23px;\">353000<\/td>\n<td style=\"text-align: center; width: 27.0296%; height: 23px;\">3100<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5193 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-3.webp\" alt=\"Abmessungen des Planetenwindenantriebs\" width=\"814\" height=\"519\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-3.webp 814w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-3-480x306.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 814px, 100vw\" \/><\/p>\n<h3>Lagertragf\u00e4higkeit<\/h3>\n<table style=\"width: 100%;\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">Typ<\/td>\n<td style=\"text-align: center;\" width=\"178\">C0 [N]<\/td>\n<td style=\"text-align: center;\" width=\"156\">Cd [N]<\/td>\n<td style=\"text-align: center;\" width=\"168\">Z [mm]<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">WD 1020<\/td>\n<td style=\"text-align: center;\">330000<\/td>\n<td style=\"text-align: center;\">183000<\/td>\n<td style=\"text-align: center;\">17.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">WD 1520<\/td>\n<td style=\"text-align: center;\">435000<\/td>\n<td style=\"text-align: center;\">224000<\/td>\n<td style=\"text-align: center;\">19.7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">WD 2000<\/td>\n<td style=\"text-align: center;\">435000<\/td>\n<td style=\"text-align: center;\">224000<\/td>\n<td style=\"text-align: center;\">25.2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">WD 2520<\/td>\n<td style=\"text-align: center;\">620000<\/td>\n<td style=\"text-align: center;\">315000<\/td>\n<td style=\"text-align: center;\">21<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">WD 3000<\/td>\n<td style=\"text-align: center;\">620000<\/td>\n<td style=\"text-align: center;\">315000<\/td>\n<td style=\"text-align: center;\">20.75<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">WD 4800<\/td>\n<td style=\"text-align: center;\">800000<\/td>\n<td style=\"text-align: center;\">390000<\/td>\n<td style=\"text-align: center;\">13.25<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">WD 8000<\/td>\n<td style=\"text-align: center;\">840000<\/td>\n<td style=\"text-align: center;\">405000<\/td>\n<td style=\"text-align: center;\">14.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"240\">WD 16000<\/td>\n<td style=\"text-align: center;\">147000<\/td>\n<td style=\"text-align: center;\">700000<\/td>\n<td style=\"text-align: center;\">13.5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5194 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-4.webp\" alt=\"Abmessungen des Planetenwindenantriebs\" width=\"1374\" height=\"682\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-4.webp 1374w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-4-1280x635.webp 1280w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-4-980x486.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-4-480x238.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1374px, 100vw\" \/><\/p>\n<h3>Allgemeine Abmessungen<\/h3>\n<table style=\"width: 100%;\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">Typ<\/td>\n<td style=\"text-align: center;\" width=\"62\">A<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">B<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">E<\/td>\n<td style=\"text-align: center;\" width=\"62\">F<\/td>\n<td style=\"text-align: center;\" width=\"72\">G<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">L<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">M<\/td>\n<td style=\"text-align: center;\" width=\"62\">N<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"62\">P<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Q<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">R<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"62\">Y<\/td>\n<td style=\"text-align: center;\" width=\"72\">Z<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 512<\/td>\n<td style=\"text-align: center;\">262<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">215 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">246 f7<\/td>\n<td style=\"text-align: center;\">271<\/td>\n<td style=\"text-align: center;\">291<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">246.5<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">75<\/td>\n<td style=\"text-align: center;\">11<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">10<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 M12<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 \u00d813<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">240<\/td>\n<td style=\"text-align: center;\">20<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 513<\/td>\n<td style=\"text-align: center;\">262<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">215 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">246 f7<\/td>\n<td style=\"text-align: center;\">271<\/td>\n<td style=\"text-align: center;\">291<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">289.5<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">75<\/td>\n<td style=\"text-align: center;\">11<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">10<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 M12<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 \u00d813<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">240<\/td>\n<td style=\"text-align: center;\">20<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 612<\/td>\n<td style=\"text-align: center;\">262<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">215 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">246 f7<\/td>\n<td style=\"text-align: center;\">271<\/td>\n<td style=\"text-align: center;\">291<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">251<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">75<\/td>\n<td style=\"text-align: center;\">11<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">10<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 M12<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 \u00d813<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">240<\/td>\n<td style=\"text-align: center;\">20<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 613<\/td>\n<td style=\"text-align: center;\">262<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">215 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">246 f7<\/td>\n<td style=\"text-align: center;\">271<\/td>\n<td style=\"text-align: center;\">291<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">293<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">75<\/td>\n<td style=\"text-align: center;\">11<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">10<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 M12<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 \u00d813<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">240<\/td>\n<td style=\"text-align: center;\">20<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 812<\/td>\n<td style=\"text-align: center;\">330<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">270 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">297 f7<\/td>\n<td style=\"text-align: center;\">327<\/td>\n<td style=\"text-align: center;\">352<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">305<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">100<\/td>\n<td style=\"text-align: center;\">6<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">12<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 M16<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 \u00d817<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">300<\/td>\n<td style=\"text-align: center;\">26.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 813<\/td>\n<td style=\"text-align: center;\">330<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">270 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">297 f7<\/td>\n<td style=\"text-align: center;\">327<\/td>\n<td style=\"text-align: center;\">352<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">348.5<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">100<\/td>\n<td style=\"text-align: center;\">6<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">12<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 M16<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 \u00d817<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">300<\/td>\n<td style=\"text-align: center;\">26.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 1022<\/td>\n<td style=\"text-align: center;\">330<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">270 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">297 f7<\/td>\n<td style=\"text-align: center;\">327<\/td>\n<td style=\"text-align: center;\">352<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">340<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">100<\/td>\n<td style=\"text-align: center;\">6<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">12<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 M16<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 \u00d817<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">300<\/td>\n<td style=\"text-align: center;\">26.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 1023<\/td>\n<td style=\"text-align: center;\">330<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">270 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">297 f7<\/td>\n<td style=\"text-align: center;\">327<\/td>\n<td style=\"text-align: center;\">352<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">395.5<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">100<\/td>\n<td style=\"text-align: center;\">6<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">12<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 M16<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12 \u00d817<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">300<\/td>\n<td style=\"text-align: center;\">26.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 1532<\/td>\n<td style=\"text-align: center;\">393<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">320 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">352 f7<\/td>\n<td style=\"text-align: center;\">383<\/td>\n<td style=\"text-align: center;\">408<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">363<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">113<\/td>\n<td style=\"text-align: center;\">6<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">11<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 12-M20<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 16 \u00d817<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">360<\/td>\n<td style=\"text-align: center;\">34.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"126\">RW 2522<\/td>\n<td style=\"text-align: center;\">393<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">320 f7<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"72\">415 f7<\/td>\n<td style=\"text-align: center;\">448<\/td>\n<td style=\"text-align: center;\">473<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">413<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">115<\/td>\n<td style=\"text-align: center;\">6<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">24<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 16 M20<\/td>\n<td style=\"text-align: center;\" colspan=\"2\" width=\"94\">Nr. 24 \u00d817<\/td>\n<td style=\"text-align: center;\" colspan=\"2\">360<\/td>\n<td style=\"text-align: center;\">29.5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Eingabedimensionen<\/h3>\n<table style=\"border-collapse: collapse; width: 100%;\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 17.00pt;\">\n<td class=\"et2\" style=\"height: 17pt; width: 75.6pt; text-align: center;\" width=\"126\" height=\"28\"><\/td>\n<td class=\"et3\" style=\"width: 55.2pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"92\"><span class=\"font5\">C<\/span><\/td>\n<td class=\"et3\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font5\">D<\/span><\/td>\n<td class=\"et3\" style=\"width: 49.2pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"82\"><span class=\"font5\">H<\/span><\/td>\n<td class=\"et3\" style=\"width: 61.2pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"102\"><span class=\"font5\">T<\/span><\/td>\n<td class=\"et3\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font5\">U<\/span><\/td>\n<td class=\"et3\" style=\"width: 55.2pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"3\" width=\"92\"><span class=\"font5\">V<\/span><\/td>\n<td class=\"et3\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font5\">W<\/span><\/td>\n<td class=\"et3\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font5\">S1<\/span><\/td>\n<td class=\"et3\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font5\">J<\/span><\/td>\n<td class=\"et3\" style=\"width: 55.2pt; text-align: center;\" colspan=\"2\" width=\"92\"><span class=\"font5\">S2<\/span><\/td>\n<\/tr>\n<tr style=\"height: 13.00pt;\">\n<td class=\"et5\" style=\"height: 13pt; width: 75.6pt; text-align: center;\" width=\"126\" height=\"21\"><span class=\"font6\">Eingang SAE B<\/span><\/td>\n<td class=\"et6\" style=\"width: 55.2pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"92\"><span class=\"font7\">101.6 H8<\/span><\/td>\n<td class=\"et8\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font7\">DP16\/32 Z13<\/span><\/td>\n<td class=\"et10\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">138<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">10<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">8<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"3\">30<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">127<\/td>\n<td class=\"et6\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font7\">Nr. 4 M12<\/span><\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">146<\/td>\n<td class=\"et6\" style=\"width: 55.2pt; text-align: center;\" colspan=\"2\" width=\"92\"><span class=\"font7\">Nr. 2 M14<\/span><\/td>\n<\/tr>\n<tr style=\"height: 13.00pt;\">\n<td class=\"et5\" style=\"height: 13pt; width: 75.6pt; text-align: center;\" width=\"126\" height=\"21\"><span class=\"font6\">Eingang SAE C<\/span><\/td>\n<td class=\"et6\" style=\"width: 55.2pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"92\"><span class=\"font7\">127 F8<\/span><\/td>\n<td class=\"et8\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font7\">DP12\/24 Z14<\/span><\/td>\n<td class=\"et10\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">114<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">15<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">16<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"3\">48<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">162<\/td>\n<td class=\"et6\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font7\">Nr. 4 M12<\/span><\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">181<\/td>\n<td class=\"et6\" style=\"width: 55.2pt; text-align: center;\" colspan=\"2\" width=\"92\"><span class=\"font7\">Nr. 2 M16<\/span><\/td>\n<\/tr>\n<tr style=\"height: 12.75pt;\">\n<td class=\"et5\" style=\"height: 12.75pt; width: 75.6pt; text-align: center;\" width=\"126\" height=\"21\"><span class=\"font6\">Eingang SAE D<\/span><\/td>\n<td class=\"et6\" style=\"width: 55.2pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"92\"><span class=\"font7\">152,5 F8<\/span><\/td>\n<td class=\"et8\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font7\">DP8\/16 Z13<\/span><\/td>\n<td class=\"et10\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">128<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">15<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">33<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"3\">47<\/td>\n<td class=\"et12\" style=\"border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\">229<\/td>\n<td class=\"et6\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font7\">Nr. 4 M20<\/span><\/td>\n<td class=\"et17\" style=\"width: 56.4pt; border-right: 0.5pt solid #000000; text-align: center;\" colspan=\"2\" width=\"94\"><span class=\"font7\">\/<\/span><\/td>\n<td class=\"et17\" style=\"width: 55.2pt; text-align: center;\" colspan=\"2\" width=\"92\"><span class=\"font7\">\/<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Gewicht und \u00d6lmenge<\/h3>\n<table style=\"width: 100%; border-collapse: collapse;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\"><\/td>\n<td style=\"width: 29.8821%; text-align: center;\" width=\"126\">Gewicht [kg]<\/td>\n<td style=\"width: 28.2655%; text-align: center;\" width=\"262\">\u00d6lmenge [litri \u2013 Liter]<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 512<\/td>\n<td style=\"width: 29.8821%; text-align: center;\">75<\/td>\n<td style=\"width: 28.2655%; text-align: center;\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 513<\/td>\n<td style=\"width: 29.8821%; text-align: center;\">85<\/td>\n<td style=\"width: 28.2655%; text-align: center;\">2.3<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 612<\/td>\n<td style=\"width: 29.8821%; text-align: center;\">90<\/td>\n<td style=\"width: 28.2655%; text-align: center;\">2.3<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 613<\/td>\n<td style=\"width: 29.8821%; height: 23px; text-align: center;\">100<\/td>\n<td style=\"width: 28.2655%; height: 23px; text-align: center;\">2.5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 812<\/td>\n<td style=\"width: 29.8821%; height: 23px; text-align: center;\">130<\/td>\n<td style=\"width: 28.2655%; height: 23px; text-align: center;\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 813<\/td>\n<td style=\"width: 29.8821%; height: 23px; text-align: center;\">140<\/td>\n<td style=\"width: 28.2655%; height: 23px; text-align: center;\">3.5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 1022<\/td>\n<td style=\"width: 29.8821%; height: 23px; text-align: center;\">145<\/td>\n<td style=\"width: 28.2655%; height: 23px; text-align: center;\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 1023<\/td>\n<td style=\"width: 29.8821%; height: 23px; text-align: center;\">155<\/td>\n<td style=\"width: 28.2655%; height: 23px; text-align: center;\">4.2<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 1532<\/td>\n<td style=\"width: 29.8821%; height: 23px; text-align: center;\">195<\/td>\n<td style=\"width: 28.2655%; height: 23px; text-align: center;\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%; text-align: center;\" width=\"378\">RW 2522<\/td>\n<td style=\"width: 29.8821%; height: 23px; text-align: center;\">275<\/td>\n<td style=\"width: 28.2655%; height: 23px; text-align: center;\">7<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5195 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-5.webp\" alt=\"Abmessungen des Planetenwindenantriebs\" width=\"832\" height=\"492\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-5.webp 832w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Dimensions-5-480x284.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 832px, 100vw\" \/><\/p>\n<h3>Lagerbelastung<\/h3>\n<table style=\"width: 100%;\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\" width=\"272\">Typ<\/td>\n<td style=\"text-align: center;\" width=\"146\">C0 [N]<\/td>\n<td style=\"text-align: center;\" width=\"168\">Cd [N]<\/td>\n<td style=\"text-align: center;\" width=\"168\">Z [mm]<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"272\">RW 512 \u2013 RW 513<\/td>\n<td style=\"text-align: center;\">65500<\/td>\n<td style=\"text-align: center;\">72800<\/td>\n<td style=\"text-align: center;\">20<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"272\">RW 612 \u2013 RW 613<\/td>\n<td style=\"text-align: center;\">65500<\/td>\n<td style=\"text-align: center;\">72800<\/td>\n<td style=\"text-align: center;\">20<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"272\">RW 812 \u2013 RW 813<\/td>\n<td style=\"text-align: center;\">100000<\/td>\n<td style=\"text-align: center;\">106000<\/td>\n<td style=\"text-align: center;\">26.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"272\">RW 1022 \u2013 RW 1023<\/td>\n<td style=\"text-align: center;\">100000<\/td>\n<td style=\"text-align: center;\">106000<\/td>\n<td style=\"text-align: center;\">26.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"272\">RW 1532<\/td>\n<td style=\"text-align: center;\">125000<\/td>\n<td style=\"text-align: center;\">125000<\/td>\n<td style=\"text-align: center;\">34.5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\" width=\"272\">RW 2522<\/td>\n<td style=\"text-align: center;\">143000<\/td>\n<td style=\"text-align: center;\">390000<\/td>\n<td style=\"text-align: center;\">29.5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Vorteile des Planetengetriebes mit Windenantrieb f\u00fcr Rohrverleger<\/h2>\n<ul>\n<li><strong>Hohe Drehmomentkapazit\u00e4t<\/strong><br \/>\nEin Planetengetriebe f\u00fcr Windenantriebe liefert ein au\u00dfergew\u00f6hnliches Drehmoment und ist ideal f\u00fcr das Bewegen der enormen Gewichte von Rohrleitungen mit gro\u00dfem Durchmesser. Seine Konstruktion verteilt die Last gleichm\u00e4\u00dfig auf mehrere Zahnr\u00e4der, minimiert die Belastung einzelner Komponenten und gew\u00e4hrleistet so einen zuverl\u00e4ssigen Betrieb auch unter extremen Betriebsbedingungen. Dadurch ist es f\u00fcr anspruchsvolle Anwendungen unverzichtbar.<\/li>\n<li><strong>Kompaktes und platzsparendes Design<\/strong><br \/>\nDie Planetengetriebeanordnung bietet eine kompakte L\u00f6sung bei gleichzeitig hoher Leistungsdichte. Durch die direkte Integration in die Seiltrommel wird die Gesamtgr\u00f6\u00dfe des Systems reduziert, ohne Kompromisse bei Festigkeit oder Effizienz einzugehen. Diese kompakte Bauweise ist besonders vorteilhaft f\u00fcr Rohrverleger, bei denen der Platz oft begrenzt ist.<\/li>\n<li><strong>Verbesserte Effizienz und Langlebigkeit<\/strong><br \/>\nDurch die gleichm\u00e4\u00dfige Lastverteilung auf die internen Zahnr\u00e4der minimiert das Planetengetriebe den Verschlei\u00df und verl\u00e4ngert so seine Lebensdauer. Die effiziente Kraft\u00fcbertragung sorgt f\u00fcr minimale Energieverluste und senkt die Betriebskosten. Konzipiert f\u00fcr raue Umgebungen, widersteht es h\u00e4rtesten Bedingungen und gew\u00e4hrleistet so zuverl\u00e4ssige Leistung in Bau- und \u00d6l-\/Gasprojekten.<\/li>\n<li><strong>Pr\u00e4zise Steuerung f\u00fcr schwere Lasten<\/strong><br \/>\nPlanetenwindenantriebe erm\u00f6glichen eine pr\u00e4zise Drehzahlreduzierung und Drehmomentsteuerung und erlauben dem Bediener so die genaue Kontrolle \u00fcber das Heben, Senken und Positionieren schwerer Rohre. Diese Pr\u00e4zision ist bei der Rohrverlegung von entscheidender Bedeutung, da selbst geringf\u00fcgige Ungenauigkeiten zu Fehlausrichtungen oder Ineffizienzen im Betrieb f\u00fchren k\u00f6nnen.<\/li>\n<li><strong>Reibungsloser und leiser Betrieb<\/strong><br \/>\nDas einzigartige Design des Planetengetriebes gew\u00e4hrleistet einen sanfteren Eingriff der Zahnr\u00e4der, wodurch Vibrationen und Ger\u00e4usche im Betrieb reduziert werden. Dies erh\u00f6ht nicht nur den Bedienkomfort, sondern verringert auch den Verschlei\u00df umliegender Bauteile und tr\u00e4gt somit zur Gesamteffizienz und Langlebigkeit des Seilwindensystems des Rohrverlegers bei.<\/li>\n<li><strong>Anpassbar f\u00fcr spezifische Anwendungen<\/strong><br \/>\nPlanetengetriebe f\u00fcr Windenantriebe lassen sich an die spezifischen Anforderungen verschiedener Rohrleitungsbauprojekte anpassen. Ob es um die Anpassung von \u00dcbersetzungsverh\u00e4ltnissen, Drehmomentkapazit\u00e4ten oder Materialspezifikationen geht \u2013 die individuelle Anpassung gew\u00e4hrleistet eine optimale Leistung des Getriebes f\u00fcr die jeweiligen Betriebsanforderungen und erh\u00f6ht die Vielseitigkeit in unterschiedlichen Bau- und Rohrleitungsumgebungen.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5236 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Gearbox-for-Pipelayers.webp\" alt=\"Planetengetriebe f\u00fcr Windenantriebe f\u00fcr Rohrleger\" width=\"1200\" height=\"750\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Gearbox-for-Pipelayers.webp 1200w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Gearbox-for-Pipelayers-980x613.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-Gearbox-for-Pipelayers-480x300.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/p>\n<h2>Anwendungen f\u00fcr Planetengetriebe f\u00fcr Winden<\/h2>\n<ul>\n<li><strong>\u00d6l- und Gasindustrie<\/strong><br \/>\nPlanetengetriebe f\u00fcr Windenantriebe spielen eine entscheidende Rolle im \u00d6l- und Gassektor, insbesondere bei der Verlegung von Rohrleitungen mit gro\u00dfem Durchmesser. Diese Getriebe gew\u00e4hrleisten die pr\u00e4zise Steuerung und Handhabung schwerer Rohre, selbst unter rauen Bedingungen auf See oder in abgelegenen Gebieten, wo Zuverl\u00e4ssigkeit und Langlebigkeit f\u00fcr die Effizienz unerl\u00e4sslich sind.<\/li>\n<li><strong>Bauindustrie<\/strong><br \/>\nIm Bauwesen werden Planetengetriebe f\u00fcr Seilwinden in schweren Baumaschinen wie Kr\u00e4nen und Rohrverlegemaschinen zum Heben und Positionieren gro\u00dfer Bauteile eingesetzt. Ihre kompakte Bauweise, das hohe Drehmoment und die pr\u00e4zise Steuerung machen sie ideal f\u00fcr die Bew\u00e4ltigung schwerer Lasten in anspruchsvollen Bauprojekten und gew\u00e4hrleisten so Betriebsgenauigkeit und Sicherheit.<\/li>\n<li><strong>Schiffs- und Offshoretechnik<\/strong><br \/>\nDie maritime Industrie setzt Planetenwindenantriebe f\u00fcr Aufgaben wie Ankerhandling, Schleppen und Unterwasserbau ein. Ihre F\u00e4higkeit, unter hohen Lasten und in anspruchsvollen Meeresumgebungen, einschlie\u00dflich Salzwasser, effizient zu arbeiten, macht sie unverzichtbar f\u00fcr Offshore-Engineering und Tiefsee-Rohrverlegung.<\/li>\n<li><strong>Bergbau und Ausgrabung<\/strong><br \/>\nPlanetengetriebe finden breite Anwendung im Bergbau zur Steuerung schwerer Hebezeuge wie Sch\u00fcrfk\u00fcbelbagger und Winden. Sie liefern das notwendige Drehmoment und die erforderliche Kontrolle zum Heben und Transportieren schwerer Materialien und gew\u00e4hrleisten so einen reibungslosen und effizienten Betrieb auch unter anspruchsvollen Bedingungen, sowohl im Untertage- als auch im Tagebau.<\/li>\n<li><strong>Sektor Erneuerbare Energien<\/strong><br \/>\nIn der Branche der erneuerbaren Energien, insbesondere bei Offshore-Windparks, werden Windenantriebsgetriebe f\u00fcr die Kabelverlegung und den Ger\u00e4tetransport eingesetzt. Ihre F\u00e4higkeit, schwere Lasten pr\u00e4zise zu steuern, gew\u00e4hrleistet die effiziente Installation von Stromkabeln und -komponenten und tr\u00e4gt so zum Ausbau einer nachhaltigen Energieinfrastruktur bei.<\/li>\n<\/ul>\n<table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5175 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Marine-and-Offshore-Industry.webp\" alt=\"Planetengetriebe f\u00fcr die Schifffahrt und Offshore-Industrie\" width=\"1200\" height=\"780\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Marine-and-Offshore-Industry.webp 1200w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Marine-and-Offshore-Industry-980x637.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Marine-and-Offshore-Industry-480x312.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5174 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Construction-Industry.webp\" alt=\"Planetenwindenantrieb f\u00fcr die Bauindustrie\" width=\"1200\" height=\"780\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Construction-Industry.webp 1200w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Construction-Industry-980x637.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Construction-Industry-480x312.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>Marine- und Offshore-Industrie<\/strong><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>Bauindustrie<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5187 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Oil-and-Gas-Industry.webp\" alt=\"Planetengetriebe f\u00fcr die \u00d6l- und Gasindustrie\" width=\"1200\" height=\"780\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Oil-and-Gas-Industry.webp 1200w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Oil-and-Gas-Industry-980x637.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Oil-and-Gas-Industry-480x312.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5176 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Mining-Industry.webp\" alt=\"Planetenwindenantrieb f\u00fcr die Bergbauindustrie\" width=\"1200\" height=\"780\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Mining-Industry.webp 1200w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Mining-Industry-980x637.webp 980w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Planetary-Winch-Drive-for-Mining-Industry-480x312.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%; text-align: center;\"><strong>\u00d6l- und Gasindustrie<\/strong><\/td>\n<td style=\"width: 50%; text-align: center;\"><strong>Bergbau<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Fehlersuche am Planetengetriebe der Rohrverlegewinde<\/h2>\n<ul>\n<li><strong>\u00dcberm\u00e4\u00dfiger L\u00e4rm oder Vibrationen<\/strong><br \/>\nWenn das Planetengetriebe eines Rohrverlegewindenantriebs ungew\u00f6hnliche Ger\u00e4usche oder Vibrationen verursacht, kann dies auf eine Fehlausrichtung der Zahnr\u00e4der, verschlissene Lager oder unzureichende Schmierung hindeuten. Pr\u00fcfen Sie die Zahnr\u00e4der auf Besch\u00e4digungen, kontrollieren Sie die Ausrichtung der internen Bauteile und stellen Sie sicher, dass das Getriebe mit dem empfohlenen \u00d6l geschmiert ist.<\/li>\n<li><strong>\u00dcberhitzung w\u00e4hrend des Betriebs<\/strong><br \/>\n\u00dcberhitzung kann durch \u00dcberlastung, unzureichende Schmierung oder blockierte Bel\u00fcftung verursacht werden. Stellen Sie sicher, dass das Getriebe nicht \u00fcberlastet ist und seine Drehmomentkapazit\u00e4t nicht \u00fcberschreitet, entfernen Sie jegliche Ablagerungen, die die K\u00fchl\u00f6ffnungen blockieren, und vergewissern Sie sich, dass die korrekten Schmierstoffmengen und -sorten verwendet werden, um optimale Betriebstemperaturen zu gew\u00e4hrleisten.<\/li>\n<li><strong>Reduziertes Drehmoment<\/strong><br \/>\nEin sp\u00fcrbarer Drehmomentverlust kann durch internen Zahnradverschlei\u00df, durchrutschende Kupplungen oder verschlissene Dichtungen mit \u00d6laustritt verursacht werden. Pr\u00fcfen Sie die Zahnr\u00e4der auf Verschlei\u00df, ziehen Sie durchrutschende Kupplungen fest oder ersetzen Sie diese und kontrollieren Sie die Dichtungen auf \u00d6llecks, um die einwandfreie Funktion wiederherzustellen.<\/li>\n<li><strong>\u00d6llecks oder -verunreinigung<\/strong><br \/>\n\u00d6llecks oder -verunreinigungen k\u00f6nnen erhebliche Sch\u00e4den am Planetengetriebe verursachen. Pr\u00fcfen Sie Dichtungen, Dichtringe und Geh\u00e4use auf Risse oder Verschlei\u00df. Ersetzen Sie besch\u00e4digte Bauteile und verwenden Sie ausschlie\u00dflich sauberes, unbelastetes \u00d6l. Regelm\u00e4\u00dfige \u00d6lanalysen helfen, Verunreinigungen fr\u00fchzeitig zu erkennen und teure Reparaturen zu vermeiden.<\/li>\n<li><strong>Startschwierigkeiten oder Abw\u00fcrgen unter Last<\/strong><br \/>\nWenn das Getriebe nur schwer anspringt oder unter Last abw\u00fcrgt, kann dies auf eine unzureichende Stromversorgung, besch\u00e4digte Zahnr\u00e4der oder interne Blockaden hindeuten. \u00dcberpr\u00fcfen Sie die Stromzufuhr zum Windensystem, untersuchen Sie die Zahnr\u00e4der auf Besch\u00e4digungen und stellen Sie sicher, dass keine Blockaden im Getriebemechanismus vorliegen.<\/li>\n<li><strong>Unregelm\u00e4\u00dfige Geschwindigkeit oder Kontrollprobleme<\/strong><br \/>\nUnregelm\u00e4\u00dfige Drehzahlen oder Steuerungsausf\u00e4lle entstehen h\u00e4ufig durch verschlissene Lager, besch\u00e4digte Planetenr\u00e4der oder falsche \u00dcbersetzungsverh\u00e4ltnisse. Pr\u00fcfen Sie die Lager auf Verschlei\u00df oder Defekte, untersuchen Sie das Planetenradsystem auf Besch\u00e4digungen und vergewissern Sie sich, dass das Getriebe auf die Drehzahl- und Drehmomentanforderungen der Rohrverlegeausr\u00fcstung abgestimmt ist.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5237 size-full\" src=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Winch-Drive-Planetary-Gearbox-for-Pipelayers.webp\" alt=\"Planetengetriebe mit Seilwindenantrieb f\u00fcr Rohrverleger\" width=\"800\" height=\"800\" srcset=\"https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Winch-Drive-Planetary-Gearbox-for-Pipelayers.webp 800w, https:\/\/korea-transmission.com\/wp-content\/uploads\/2025\/09\/Winch-Drive-Planetary-Gearbox-for-Pipelayers-480x480.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Ein Planetengetriebe f\u00fcr Rohrverlegemaschinen ist eine spezielle mechanische Komponente zur Leistungssteigerung von Windensystemen in Rohrverlegemaschinen. Es wird zur Verlegung von Rohrleitungen mit gro\u00dfem Durchmesser im Bauwesen und in der \u00d6l- und Gasindustrie eingesetzt. Das Planetengetriebe besteht aus einem zentralen Sonnenrad, mehreren darum kreisenden Planetenr\u00e4dern und einem \u00e4u\u00dferen Hohlrad. Alle Komponenten sind in einem kompakten, rotierenden Geh\u00e4use untergebracht. Direkt in die Windentrommel integriert, erm\u00f6glicht es die effiziente \u00dcbertragung hoher Drehmomente und Drehzahlreduzierungen und somit die pr\u00e4zise Steuerung des Hebens, Senkens und Positionierens schwerer Rohre.<\/p>","protected":false},"featured_media":5120,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[208,194],"product_tag":[200,203,201,202,199,209,210,211],"class_list":{"0":"post-5235","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-planetary-winch-drive","7":"product_cat-planetary-gearboxes","8":"product_tag-planetary-gear-reducers","9":"product_tag-planetary-gearbox-for-sale","10":"product_tag-planetary-gearbox-manufacturers","11":"product_tag-planetary-gearbox-suppliers","12":"product_tag-planetary-gearboxes","13":"product_tag-planetary-winch-drive","14":"product_tag-planetary-winch-drive-gearbox","15":"product_tag-winch-drive-planetary-gearbox","17":"first","18":"instock","19":"shipping-taxable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/product\/5235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/comments?post=5235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/media\/5120"}],"wp:attachment":[{"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/media?parent=5235"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/product_brand?post=5235"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/product_cat?post=5235"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/korea-transmission.com\/de\/wp-json\/wp\/v2\/product_tag?post=5235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}